{"id":10940,"date":"2024-07-13T18:49:15","date_gmt":"2024-07-13T16:49:15","guid":{"rendered":"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/"},"modified":"2024-07-13T18:49:16","modified_gmt":"2024-07-13T16:49:16","slug":"euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas","status":"publish","type":"post","link":"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/","title":{"rendered":"Euro 2024 : l&#39;Angleterre doit modifier sa composition pour la demi-finale contre les Pays-Bas"},"content":{"rendered":"<p>L&#39;ancien arri\u00e8re gauche anglais Stephen Warnock exhorte Gareth Southgate \u00e0 d\u00e9placer Kieran Trippier de ce poste pour la demi-finale de l&#39;Euro 2024 contre les Pays-Bas.<\/p>\n<div id=\"article_body\" itemprop=\"articleBody\">\n<h3 class=\"firstPara\">Ancien <strong class=\"autotag\">Angleterre<\/strong> international <strong class=\"autotag\">Stephen Warnock<\/strong> a appel\u00e9 <strong class=\"autotag\">Gareth Southgate<\/strong> pour changer la position de l&#39;arri\u00e8re gauche pour mercredi <strong class=\"autotag\">Euro 2024<\/strong> demi-finale contre <strong class=\"autotag\">Pays-Bas<\/strong>.<\/h3>\n<p>Les Trois Lions tenteront d&#39;atteindre une deuxi\u00e8me finale cons\u00e9cutive du Championnat d&#39;Europe lorsqu&#39;ils affronteront <strong class=\"autotag\">Ronald Koeman<\/strong>Les hommes de Dortmund, qui ont b\u00e9gay\u00e9 jusqu&#39;\u00e0 pr\u00e9sent pour atteindre le dernier carr\u00e9.<\/p>\n<p>L&#39;Angleterre n&#39;a gagn\u00e9 qu&#39;une seule fois en 90 minutes lors du tournoi de cet \u00e9t\u00e9 &#8211; une victoire 1-0 contre la Serbie lors de son match d&#39;ouverture &#8211; et a eu besoin d&#39;\u00e9galiser en fin de match lors des deux matches \u00e0 \u00e9limination directe avant de battre la Slovaquie et la Croatie. <strong class=\"autotag\">Suisse<\/strong> respectivement en prolongation et aux tirs au but.<\/p>\n<p>Southgate a chang\u00e9 de formation pour le match contre la Suisse, jouant \u00e0 trois \u00e0 l&#39;arri\u00e8re avec <strong class=\"autotag\">Bukayo Saka<\/strong> et <strong class=\"autotag\">Kieran Trippier<\/strong> en tant qu&#39;arri\u00e8res lat\u00e9raux.<\/p>\n<p>Saka a d\u00e9but\u00e9 sur le c\u00f4t\u00e9 droit malgr\u00e9 son c\u00f4t\u00e9 gaucher, tandis que Trippier \u00e9tait sur le c\u00f4t\u00e9 gauche malgr\u00e9 son c\u00f4t\u00e9 droitier, et ce dernier en particulier a \u00e9t\u00e9 critiqu\u00e9 \u00e0 plusieurs reprises tout au long du tournoi pour avoir coup\u00e9 trop souvent vers l&#39;int\u00e9rieur par rapport \u00e0 un arri\u00e8re gauche naturel.<\/p>\n<p class=\"imgI\">\n<h2 class=\"k3\">Trippier \u00ab ralentit l&#39;Angleterre \u00bb \u00e0 gauche<\/h2>\n<p>Warnock conna\u00eet bien le poste d&#39;arri\u00e8re gauche gr\u00e2ce \u00e0 sa carri\u00e8re de joueur et y a jou\u00e9 deux fois pour l&#39;Angleterre, et il pense qu&#39;un gaucher naturel am\u00e9liorerait l&#39;\u00e9quilibre g\u00e9n\u00e9ral de l&#39;\u00e9quipe de Southgate, s&#39;il s&#39;en tient \u00e0 la formation du match contre la Suisse.<\/p>\n<p>\u00ab\u00a0Je pense que la raison [the three-at-the-back formation] \u00e7a marche parce que tu essaies d&#39;obtenir [Jude] Bellingham et [Phil] Foden dans cette position derri\u00e8re <strong class=\"autotag\">Harry Kane<\/strong>\u00ab\u00a0, a d\u00e9clar\u00e9 Warnock <strong>Taupe sportive<\/strong>.<\/p>\n<p>\u00ab Mais aussi, quand vous avez des lat\u00e9raux, vous pouvez les pousser plus haut sur le terrain et presser, et puis \u00e0 l&#39;arri\u00e8re, cela vous laisse trois contre deux, trois contre trois. Ce que vous faites alors, c&#39;est que vous faites confiance \u00e0 vos trois d\u00e9fenseurs centraux pour qu&#39;ils soient aussi serr\u00e9s que vous le souhaitez et qu&#39;ils soient laiss\u00e9s sur le terrain dans des situations de un contre un, m\u00eame si c&#39;est \u00e0 trois contre trois.<\/p>\n<p>\u00ab Mais vous \u00eates heureux d&#39;affronter votre homme en un contre un, je pense que \u00e7a marche. La seule chose que je trouve \u00e0 ce sujet, c&#39;est que je ne comprends toujours pas comment Saka et Trippier peuvent jouer sur les c\u00f4t\u00e9s oppos\u00e9s et \u00e0 l&#39;int\u00e9rieur.<\/p>\n<p>\u00ab\u00a0Je comprends Saka dans une certaine mesure, car il a l&#39;habitude de jouer sur ce c\u00f4t\u00e9 et il peut courir le long de la ligne assez facilement. Mais Trippier &#8211; je n&#39;ai rien contre lui, je suis un grand fan, il a \u00e9t\u00e9 magnifique en club et en s\u00e9lection &#8211; mais ce n&#39;est pas naturel pour lui de vouloir aller sur le c\u00f4t\u00e9 gauche. Il veut toujours revenir, et cela ralentit un peu l&#39;Angleterre.\u00a0\u00bb<\/p>\n<p>\u00ab S&#39;ils parviennent \u00e0 trouver cet \u00e9quilibre sur le c\u00f4t\u00e9 gauche, je pense que la formation fonctionnera vraiment bien. \u00bb<\/p>\n<p class=\"imgI\"><img decoding=\"async\" loading=\"lazy\" class=\"l\" src=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/07\/Euro-2024-l39Angleterre-doit-modifier-sa-composition-pour-la.JPG\" title=\"Bukayo Saka c\u00e9l\u00e8bre son but pour l&#39;Angleterre le 6 juillet 2024\" alt=\"Bukayo Saka c\u00e9l\u00e8bre son but pour l&#39;Angleterre le 6 juillet 2024\" width=\"640\" height=\"480\"><\/p>\n<h2 class=\"k3\">Saka est l&#39;homme principal de l&#39;Angleterre<\/h2>\n<p>Saka a r\u00e9alis\u00e9 une performance exceptionnelle lors de la victoire de l&#39;Angleterre en quart de finale contre la Suisse, \u00e9tant nomm\u00e9 \u00e0 juste titre homme du match en plus d&#39;avoir marqu\u00e9 le but \u00e9galisateur et le but lors de la s\u00e9ance de tirs au but.<\/p>\n<p>Warnock a fait l&#39;\u00e9loge de la <strong class=\"autotag\">Arsenal<\/strong> ailier, mais estime qu&#39;un changement loin de Trippier sur le c\u00f4t\u00e9 gauche aiderait Saka \u00e0 se d\u00e9marquer encore plus en tant qu&#39;homme principal de l&#39;Angleterre.<\/p>\n<p>\u00ab Si vous pouvez isoler Saka dans des situations en un contre un et tirer le meilleur parti de ses attributs, alors il se d\u00e9marquera dans la plupart des matchs \u00bb, a d\u00e9clar\u00e9 Warnock. <strong>Taupe sportive<\/strong>.<\/p>\n<p>\u00ab Il y a eu des matchs o\u00f9 il a \u00e9t\u00e9 \u00e9touff\u00e9 et o\u00f9 nous lui avons envoy\u00e9 le ballon tr\u00e8s lentement. Mais encore une fois, cela se r\u00e9sume \u00e0 l&#39;\u00e9quilibre du c\u00f4t\u00e9 gauche. Si vous jouez contre l&#39;Angleterre, vous savez que le ballon ne va effectivement aller que vers Saka, il va \u00eatre le joueur principal. <\/p>\n<p>\u00ab Qu&#39;allez-vous faire ? Vous allez mettre deux hommes de ce c\u00f4t\u00e9, vous assurer de lui rendre la t\u00e2che tr\u00e8s difficile et de lui rendre difficile de vous affronter dans des situations de un contre un. C&#39;est tr\u00e8s facile de se mettre en position contre l&#39;Angleterre en ce moment \u00e0 cause de ce d\u00e9s\u00e9quilibre. \u00bb<\/p>\n<p>L&#39;Angleterre a souffert d&#39;une p\u00e9nurie d&#39;arri\u00e8res gauches disponibles jusqu&#39;\u00e0 pr\u00e9sent \u00e0 l&#39;Euro 2024, avec <strong class=\"autotag\">Luke Shaw<\/strong> le seul joueur naturel inclus dans l&#39;\u00e9quipe malgr\u00e9 le fait que l&#39;homme de Manchester United n&#39;ait pas jou\u00e9 depuis f\u00e9vrier en raison d&#39;une blessure.<\/p>\n<p>Shaw a \u00e9galement manqu\u00e9 les quatre premiers matchs de l&#39;Angleterre lors du tournoi de cet \u00e9t\u00e9, mais a fait une apparition sur le banc contre la Suisse et pourrait \u00eatre en mesure de jouer contre les Pays-Bas lors de la demi-finale de mercredi.<\/p>\n<p><em>Stephen Warnock s&#39;adressait \u00e0 <strong>Taupe sportive<\/strong> au nom de BetVictor.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&#39;ancien arri\u00e8re gauche anglais Stephen Warnock exhorte Gareth Southgate \u00e0 d\u00e9placer Kieran Trippier de ce poste pour la demi-finale de l&#39;Euro 2024 contre les Pays-Bas.<\/p>\n","protected":false},"author":1,"featured_media":10941,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[2291,20,2294,578,5403,4294,93,5749,1090,51],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Euro 2024 : l&#039;Angleterre doit modifier sa composition pour la demi-finale contre les Pays-Bas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Euro 2024 : l&#039;Angleterre doit modifier sa composition pour la demi-finale contre les Pays-Bas\" \/>\n<meta property=\"og:description\" content=\"L&#039;ancien arri\u00e8re gauche anglais Stephen Warnock exhorte Gareth Southgate \u00e0 d\u00e9placer Kieran Trippier de ce poste pour la demi-finale de l&#039;Euro 2024 contre les Pays-Bas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/\" \/>\n<meta property=\"og:site_name\" content=\"Foot d&#039;avant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Footdavant\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-13T16:49:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-13T16:49:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/07\/Euro-2024-l39Angleterre-doit-modifier-sa-composition-pour-la.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:site\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/\"},\"author\":{\"name\":\"Cl\u00e9ment\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\"},\"headline\":\"Euro 2024 : l&#39;Angleterre doit modifier sa composition pour la demi-finale contre les Pays-Bas\",\"datePublished\":\"2024-07-13T16:49:15+00:00\",\"dateModified\":\"2024-07-13T16:49:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/\"},\"wordCount\":935,\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"keywords\":[\"composition\",\"contre\",\"demifinale\",\"doit\",\"Euro\",\"l39Angleterre\",\"les\",\"modifier\",\"PaysBas\",\"pour\"],\"articleSection\":[\"Premier League\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/\",\"name\":\"Euro 2024 : l&#39;Angleterre doit modifier sa composition pour la demi-finale contre les Pays-Bas\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\"},\"datePublished\":\"2024-07-13T16:49:15+00:00\",\"dateModified\":\"2024-07-13T16:49:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/footdavant.fr\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Euro 2024 : l&#39;Angleterre doit modifier sa composition pour la demi-finale contre les Pays-Bas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"name\":\"Foot d'avant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\",\"name\":\"Foot d'avant\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"contentUrl\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"width\":936,\"height\":549,\"caption\":\"Foot d'avant\"},\"image\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Footdavant\/\",\"https:\/\/twitter.com\/FootdavantFr\",\"https:\/\/www.instagram.com\/footdavant.fr\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\",\"name\":\"Cl\u00e9ment\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9ment\"},\"sameAs\":[\"https:\/\/footdavant.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Euro 2024 : l&#39;Angleterre doit modifier sa composition pour la demi-finale contre les Pays-Bas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/","og_locale":"fr_FR","og_type":"article","og_title":"Euro 2024 : l&#39;Angleterre doit modifier sa composition pour la demi-finale contre les Pays-Bas","og_description":"L&#39;ancien arri\u00e8re gauche anglais Stephen Warnock exhorte Gareth Southgate \u00e0 d\u00e9placer Kieran Trippier de ce poste pour la demi-finale de l&#39;Euro 2024 contre les Pays-Bas.","og_url":"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/","og_site_name":"Foot d&#039;avant","article_publisher":"https:\/\/www.facebook.com\/Footdavant\/","article_published_time":"2024-07-13T16:49:15+00:00","article_modified_time":"2024-07-13T16:49:16+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/07\/Euro-2024-l39Angleterre-doit-modifier-sa-composition-pour-la.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9ment","twitter_card":"summary_large_image","twitter_creator":"@FootdavantFr","twitter_site":"@FootdavantFr","twitter_misc":{"\u00c9crit par":"Cl\u00e9ment","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/#article","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/"},"author":{"name":"Cl\u00e9ment","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d"},"headline":"Euro 2024 : l&#39;Angleterre doit modifier sa composition pour la demi-finale contre les Pays-Bas","datePublished":"2024-07-13T16:49:15+00:00","dateModified":"2024-07-13T16:49:16+00:00","mainEntityOfPage":{"@id":"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/"},"wordCount":935,"publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"keywords":["composition","contre","demifinale","doit","Euro","l39Angleterre","les","modifier","PaysBas","pour"],"articleSection":["Premier League"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/","url":"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/","name":"Euro 2024 : l&#39;Angleterre doit modifier sa composition pour la demi-finale contre les Pays-Bas","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/#website"},"datePublished":"2024-07-13T16:49:15+00:00","dateModified":"2024-07-13T16:49:16+00:00","breadcrumb":{"@id":"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/footdavant.fr\/actualites\/euro-2024-langleterre-doit-modifier-sa-composition-pour-la-demi-finale-contre-les-pays-bas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/footdavant.fr\/actualites\/"},{"@type":"ListItem","position":2,"name":"Euro 2024 : l&#39;Angleterre doit modifier sa composition pour la demi-finale contre les Pays-Bas"}]},{"@type":"WebSite","@id":"https:\/\/footdavant.fr\/actualites\/#website","url":"https:\/\/footdavant.fr\/actualites\/","name":"Foot d'avant","description":"","publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/footdavant.fr\/actualites\/#organization","name":"Foot d'avant","url":"https:\/\/footdavant.fr\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","contentUrl":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","width":936,"height":549,"caption":"Foot d'avant"},"image":{"@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Footdavant\/","https:\/\/twitter.com\/FootdavantFr","https:\/\/www.instagram.com\/footdavant.fr\/"]},{"@type":"Person","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d","name":"Cl\u00e9ment","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","caption":"Cl\u00e9ment"},"sameAs":["https:\/\/footdavant.fr\/"]}]}},"_links":{"self":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/10940"}],"collection":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/comments?post=10940"}],"version-history":[{"count":1,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/10940\/revisions"}],"predecessor-version":[{"id":10942,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/10940\/revisions\/10942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media\/10941"}],"wp:attachment":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media?parent=10940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/categories?post=10940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/tags?post=10940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}