{"id":10946,"date":"2024-07-13T22:50:12","date_gmt":"2024-07-13T20:50:12","guid":{"rendered":"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/"},"modified":"2024-07-13T22:50:13","modified_gmt":"2024-07-13T20:50:13","slug":"actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves","status":"publish","type":"post","link":"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/","title":{"rendered":"Actualit\u00e9s et rumeurs sur les transferts : Mikautadze \u00e0 West Ham United, Clarke-Salter \u00e0 Wolves"},"content":{"rendered":"<p>Sports Mole fait le point sur les derni\u00e8res nouvelles et rumeurs de transfert, notamment celle de Georges Mikautadze \u00e0 West Ham United et celle de Jake Clarke-Salter \u00e0 Wolverhampton Wanderers. <\/p>\n<div id=\"article_body\" itemprop=\"articleBody\">\n<h3 class=\"firstPara\">\n<strong class=\"autotag\">West Ham United<\/strong> auraient soumis une offre pour <strong class=\"autotag\">Metz<\/strong> et la G\u00e9orgie en avant <strong class=\"autotag\">Georges Mikautadze<\/strong>.<\/h3>\n<p>Le joueur de 23 ans a fait irruption sur la sc\u00e8ne continentale lors de l&#39;Euro 2024 en Allemagne, o\u00f9 l&#39;attaquant a aid\u00e9 les Crusaders \u00e0 atteindre les huiti\u00e8mes de finale de la comp\u00e9tition lors de leur toute premi\u00e8re apparition dans un tournoi majeur.<\/p>\n<p>Trouvant le chemin des filets lors des trois matches de groupe de la G\u00e9orgie, Mikautadze \u00e9tait le meilleur buteur du Championnat d&#39;Europe avant la phase \u00e0 \u00e9limination directe.<\/p>\n<p>L&#39;attaquant messin n&#39;a pas r\u00e9ussi \u00e0 percer le filet espagnol <strong class=\"autotag\">Unai Simon<\/strong> en huiti\u00e8mes de finale, la Roja a enregistr\u00e9 une victoire 4-1 pour \u00e9liminer <strong class=\"autotag\">Willy Sagnol<\/strong>L&#39;\u00e9quipe de France est hors comp\u00e9tition.<\/p>\n<p>Apr\u00e8s avoir impressionn\u00e9 massivement \u00e0 l&#39;Euro 2024, Mikautadze a suscit\u00e9 l&#39;int\u00e9r\u00eat de l&#39;\u00e9quipe de Premier League West Ham, selon <em>Football Insider<\/em>.<\/p>\n<p>Le rapport affirme que les Hammers ont soumis une offre initiale pour l&#39;international de 29 fois, qui a connu une seconde moiti\u00e9 de saison prolifique au club fran\u00e7ais de Metz.<\/p>\n<p>Mikautadze a marqu\u00e9 13 buts en seulement 20 apparitions en Ligue 1, mais ces prouesses offensives n&#39;ont pas suffi \u00e0 emp\u00eacher son \u00e9quipe d&#39;\u00e9viter la rel\u00e9gation en deuxi\u00e8me division.<\/p>\n<p>Alors qu&#39;il se pr\u00e9pare \u00e0 \u00e9voluer en Ligue 2, il semble que l&#39;ancien buteur de l&#39;Ajax ne restera pas, Metz cherchant \u00e0 empocher 21,1 millions de livres sterling gr\u00e2ce \u00e0 la vente de l&#39;attaquant.<\/p>\n<p class=\"imgI\">\n<p><strong class=\"autotag\">Julen Lopetegui<\/strong> esp\u00e8re renforcer ses rangs offensifs avec la signature de <strong class=\"autotag\">Rangers de Queens Park<\/strong> d\u00e9fenseur <strong class=\"autotag\">Jake Clarke-Salter<\/strong> quelques jours seulement apr\u00e8s l&#39;acquisition du d\u00e9fenseur Max Kilman des Wolves.<\/p>\n<p>Le club de Black Country a gagn\u00e9 40 millions de livres sterling gr\u00e2ce \u00e0 la vente du d\u00e9fenseur central, avec <strong class=\"autotag\">Gary O&#39;Neil<\/strong>L&#39;\u00e9quipe est d\u00e9sormais en mission pour recruter un rempla\u00e7ant ad\u00e9quat.<\/p>\n<p>Cette recherche a conduit les Wolves \u00e0 parcourir le march\u00e9 du championnat, selon <em>Football Insider<\/em>avec Clarke-Salter int\u00e9ressant pour le club de Premier League.<\/p>\n<p>Il semblerait que l&#39;\u00e9quipe des West Midlands pr\u00e9pare un transfert estival pour l&#39;ancien d\u00e9fenseur de Chelsea, qui a jou\u00e9 49 fois pour les R&#39;s depuis son transfert permanent de Stamford Bridge en 2022.<\/p>\n<p>Clarke-Salter aurait \u00e9t\u00e9 observ\u00e9 par les Wolves pendant les derni\u00e8res \u00e9tapes de la campagne 2023-24, lorsque <strong class=\"autotag\">Mart\u00ed Cifuentes<\/strong>Les troupes de &#39;s ont produit une riche s\u00e9rie de r\u00e9sultats pour \u00e9viter une bataille pour la rel\u00e9gation en deuxi\u00e8me division.<\/p>\n<p>En raison de ses performances impressionnantes, le joueur de 26 ans s&#39;attend \u00e0 des avanc\u00e9es cet \u00e9t\u00e9 et QPR se pr\u00e9pare en pr\u00e9vision des offres entrantes pour son capitaine.<\/p>\n<p>Les autres options de d\u00e9fenseur central des R incluent <strong class=\"autotag\">Jimmy Dunne<\/strong>, <strong class=\"autotag\">Morgan Fox<\/strong> et <strong class=\"autotag\">Steve Cook<\/strong>ces deux derniers \u00e9tant au cr\u00e9puscule de leur carri\u00e8re.<\/p>\n<p class=\"imgI\"><img decoding=\"async\" loading=\"lazy\" class=\"l\" src=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/07\/Actualites-et-rumeurs-sur-les-transferts-Mikautadze-a-West.JPG\" title=\"L&#39;entra\u00eeneur-chef de Leeds United, Daniel Farke, le 12 mai 2024.\" alt=\"L&#39;entra\u00eeneur-chef de Leeds United, Daniel Farke, le 12 mai 2024.\" width=\"640\" height=\"480\"><\/p>\n<p>En se concentrant sur un joueur qui pourrait participer au championnat cet \u00e9t\u00e9, <strong class=\"autotag\">Ville de Salford<\/strong> ont perdu leur gardien de but de premier choix au profit de Leeds United.<\/p>\n<p>Alex Cairns a disput\u00e9 un total de 51 matches pour l&#39;\u00e9quipe de League Two dans toutes les comp\u00e9titions la saison derni\u00e8re, gardant huit feuilles blanches en quatri\u00e8me division.<\/p>\n<p>Malgr\u00e9 son importance pour Salford, le joueur de 31 ans est parti apr\u00e8s seulement deux ans pour rejoindre les g\u00e9ants du Yorkshire, Leeds.<\/p>\n<p>Il semblerait que les Blancs aient accept\u00e9 une offre \u00e0 six chiffres pour le gardien, les conditions personnelles entre le joueur et le club acheteur ayant \u00e9t\u00e9 facilement convenues.<\/p>\n<p>Il restait 12 mois \u00e0 Cairns sur son contrat au Peninsula Stadium, o\u00f9 Salford entamera son sixi\u00e8me mandat cons\u00e9cutif en League Two \u00e0 la mi-ao\u00fbt.<\/p>\n<p>L&#39;ancien joueur de Rotherham United aidera Leeds \u00e0 remplir son quota de joueurs locaux, chaque club de l&#39;EFL \u00e9tant tenu de nommer au moins huit joueurs locaux dans son \u00e9quipe de 25 joueurs.<\/p>\n<p>Cairns ne devrait pas d\u00e9fier Illian Meslier pour le statut de premier choix \u00e0 Elland Road, o\u00f9 <strong class=\"autotag\">Daniel Farke<\/strong>L&#39;\u00e9quipe de s&#39;efforcera d&#39;obtenir la promotion en Premier League.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sports Mole fait le point sur les derni\u00e8res nouvelles et rumeurs de transfert, notamment celle de Georges Mikautadze \u00e0 West Ham United et celle de<\/p>\n","protected":false},"author":1,"featured_media":10947,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[7,5751,286,93,5554,976,103,1376,13,285,1454],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Actualit\u00e9s et rumeurs sur les transferts : Mikautadze \u00e0 West Ham United, Clarke-Salter \u00e0 Wolves<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualit\u00e9s et rumeurs sur les transferts : Mikautadze \u00e0 West Ham United, Clarke-Salter \u00e0 Wolves\" \/>\n<meta property=\"og:description\" content=\"Sports Mole fait le point sur les derni\u00e8res nouvelles et rumeurs de transfert, notamment celle de Georges Mikautadze \u00e0 West Ham United et celle de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/\" \/>\n<meta property=\"og:site_name\" content=\"Foot d&#039;avant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Footdavant\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-13T20:50:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-13T20:50:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/07\/Actualites-et-rumeurs-sur-les-transferts-Mikautadze-a-West.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:site\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/\"},\"author\":{\"name\":\"Cl\u00e9ment\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\"},\"headline\":\"Actualit\u00e9s et rumeurs sur les transferts : Mikautadze \u00e0 West Ham United, Clarke-Salter \u00e0 Wolves\",\"datePublished\":\"2024-07-13T20:50:12+00:00\",\"dateModified\":\"2024-07-13T20:50:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/\"},\"wordCount\":723,\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"keywords\":[\"Actualit\u00e9s\",\"ClarkeSalter\",\"Ham\",\"les\",\"Mikautadze\",\"rumeurs\",\"sur\",\"transferts\",\"United\",\"West\",\"Wolves\"],\"articleSection\":[\"Premier League\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/\",\"name\":\"Actualit\u00e9s et rumeurs sur les transferts : Mikautadze \u00e0 West Ham United, Clarke-Salter \u00e0 Wolves\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\"},\"datePublished\":\"2024-07-13T20:50:12+00:00\",\"dateModified\":\"2024-07-13T20:50:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/footdavant.fr\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s et rumeurs sur les transferts : Mikautadze \u00e0 West Ham United, Clarke-Salter \u00e0 Wolves\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"name\":\"Foot d'avant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\",\"name\":\"Foot d'avant\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"contentUrl\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"width\":936,\"height\":549,\"caption\":\"Foot d'avant\"},\"image\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Footdavant\/\",\"https:\/\/twitter.com\/FootdavantFr\",\"https:\/\/www.instagram.com\/footdavant.fr\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\",\"name\":\"Cl\u00e9ment\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9ment\"},\"sameAs\":[\"https:\/\/footdavant.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actualit\u00e9s et rumeurs sur les transferts : Mikautadze \u00e0 West Ham United, Clarke-Salter \u00e0 Wolves","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/","og_locale":"fr_FR","og_type":"article","og_title":"Actualit\u00e9s et rumeurs sur les transferts : Mikautadze \u00e0 West Ham United, Clarke-Salter \u00e0 Wolves","og_description":"Sports Mole fait le point sur les derni\u00e8res nouvelles et rumeurs de transfert, notamment celle de Georges Mikautadze \u00e0 West Ham United et celle de","og_url":"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/","og_site_name":"Foot d&#039;avant","article_publisher":"https:\/\/www.facebook.com\/Footdavant\/","article_published_time":"2024-07-13T20:50:12+00:00","article_modified_time":"2024-07-13T20:50:13+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/07\/Actualites-et-rumeurs-sur-les-transferts-Mikautadze-a-West.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9ment","twitter_card":"summary_large_image","twitter_creator":"@FootdavantFr","twitter_site":"@FootdavantFr","twitter_misc":{"\u00c9crit par":"Cl\u00e9ment","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/#article","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/"},"author":{"name":"Cl\u00e9ment","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d"},"headline":"Actualit\u00e9s et rumeurs sur les transferts : Mikautadze \u00e0 West Ham United, Clarke-Salter \u00e0 Wolves","datePublished":"2024-07-13T20:50:12+00:00","dateModified":"2024-07-13T20:50:13+00:00","mainEntityOfPage":{"@id":"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/"},"wordCount":723,"publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"keywords":["Actualit\u00e9s","ClarkeSalter","Ham","les","Mikautadze","rumeurs","sur","transferts","United","West","Wolves"],"articleSection":["Premier League"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/","url":"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/","name":"Actualit\u00e9s et rumeurs sur les transferts : Mikautadze \u00e0 West Ham United, Clarke-Salter \u00e0 Wolves","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/#website"},"datePublished":"2024-07-13T20:50:12+00:00","dateModified":"2024-07-13T20:50:13+00:00","breadcrumb":{"@id":"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/footdavant.fr\/actualites\/actualites-et-rumeurs-sur-les-transferts-mikautadze-a-west-ham-united-clarke-salter-a-wolves\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/footdavant.fr\/actualites\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s et rumeurs sur les transferts : Mikautadze \u00e0 West Ham United, Clarke-Salter \u00e0 Wolves"}]},{"@type":"WebSite","@id":"https:\/\/footdavant.fr\/actualites\/#website","url":"https:\/\/footdavant.fr\/actualites\/","name":"Foot d'avant","description":"","publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/footdavant.fr\/actualites\/#organization","name":"Foot d'avant","url":"https:\/\/footdavant.fr\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","contentUrl":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","width":936,"height":549,"caption":"Foot d'avant"},"image":{"@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Footdavant\/","https:\/\/twitter.com\/FootdavantFr","https:\/\/www.instagram.com\/footdavant.fr\/"]},{"@type":"Person","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d","name":"Cl\u00e9ment","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","caption":"Cl\u00e9ment"},"sameAs":["https:\/\/footdavant.fr\/"]}]}},"_links":{"self":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/10946"}],"collection":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/comments?post=10946"}],"version-history":[{"count":1,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/10946\/revisions"}],"predecessor-version":[{"id":10948,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/10946\/revisions\/10948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media\/10947"}],"wp:attachment":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media?parent=10946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/categories?post=10946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/tags?post=10946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}