{"id":11033,"date":"2024-07-15T20:48:27","date_gmt":"2024-07-15T18:48:27","guid":{"rendered":"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/"},"modified":"2024-07-15T20:48:28","modified_gmt":"2024-07-15T18:48:28","slug":"le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool","status":"publish","type":"post","link":"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/","title":{"rendered":"Le WR des Vikings Jordan Addison a \u00e9t\u00e9 arr\u00eat\u00e9 vendredi dernier pour suspicion de conduite sous l&#39;emprise de l&#39;alcool"},"content":{"rendered":"<div>\n<p>Il a \u00e9t\u00e9 arr\u00eat\u00e9 \u00e0 23h36 HNE et a \u00e9t\u00e9 lib\u00e9r\u00e9 samedi \u00e0 1h36 HNE. La limite l\u00e9gale pour conduire en Californie est de 0,08. Les agents n&#39;ont pas encore rendu public le taux d&#39;alcool\u00e9mie d&#39;Addison. Dans une d\u00e9claration publi\u00e9e par les Vikings, l&#39;\u00e9quipe a d\u00e9clar\u00e9 qu&#39;elle \u00e9tait au courant de l&#39;arrestation d&#39;Addison et qu&#39;elle travaillait \u00e0 recueillir plus d&#39;informations.<\/p>\n<h2>Jordan Addison a \u00e9t\u00e9 arr\u00eat\u00e9 ce week-end pour suspicion de conduite sous l&#39;emprise de l&#39;alcool<\/h2>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Il y a une semaine, le d\u00e9fenseur des Vikings Khyree Jackson a \u00e9t\u00e9 tu\u00e9 par un conducteur ivre.<\/p>\n<p>Aujourd&#39;hui, le WR des Vikings Jordan Addison aurait conduit en \u00e9tat d&#39;ivresse.<\/p>\n<p>Boire et conduire tue des gens et pourtant les joueurs de la NFL refusent de respecter la loi.<\/p>\n<p>Roger Goodell doit prendre cela au s\u00e9rieux. <a rel=\"nofollow\" href=\"https:\/\/t.co\/nvfSaFdXoP\">pic.twitter.com\/nvfSaFdXoP<\/a><\/p>\n<p>\u2014 Notifications de la NFL (@NFLNotify) <a rel=\"nofollow\" href=\"https:\/\/twitter.com\/NFLNotify\/status\/1812638347900453366?ref_src=twsrc%5Etfw\">15 juillet 2024<\/a><\/p>\n<\/blockquote>\n<p>Jordan Addison a \u00e9t\u00e9 arr\u00eat\u00e9 pour suspicion de conduite en \u00e9tat d&#39;ivresse cinq jours seulement apr\u00e8s que son co\u00e9quipier d\u00e9butant Khyree Jackson a \u00e9t\u00e9 tu\u00e9 par un conducteur ivre. Ce n&#39;est pas une bonne image pour Addison ou la franchise des Vikings. De plus, il s&#39;agit du deuxi\u00e8me incident li\u00e9 \u00e0 la conduite pour Addison en un an. En juillet 2023, Addison a \u00e9t\u00e9 cit\u00e9 pour avoir conduit \u00e0 140 mph sur l&#39;autoroute du Minnesota. Un geste imprudent de la part de l&#39;ancien choix de premier tour. Il a accept\u00e9 de plaider coupable \u00e0 un d\u00e9lit d&#39;exc\u00e8s de vitesse, et une accusation de conduite imprudente a \u00e9t\u00e9 rejet\u00e9e. Addison a pay\u00e9 686 $ d&#39;amendes.<\/p>\n<p>Quelqu&#39;un dans la franchise des Vikings doit s&#39;asseoir avec Addison et discuter de ses actions. Le talentueux WR est un \u00e9l\u00e9ment pr\u00e9cieux pour le Minnesota. Il met lui-m\u00eame et les autres en danger en buvant et en \u00e9tant au volant. Addison sort d&#39;une premi\u00e8re saison productive avec les Vikings en 2023. Le joueur de 22 ans a jou\u00e9 dans les 17 matchs et a \u00e9t\u00e9 titulaire \u00e0 14 reprises. Il a r\u00e9alis\u00e9 70 r\u00e9ceptions sur 108 cibles pour 911 yards et 10 touchdowns en r\u00e9ception. Lorsque Justin Jefferson \u00e9tait absent la saison derni\u00e8re, Addison a pris le relais en tant que recrue et \u00e9tait leur WR1.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">En tant que fan de Jordan Addison et que j&#39;adore en tant que joueur depuis qu&#39;il \u00e9tait \u00e0 l&#39;USC, je suis plus que d\u00e9\u00e7u. En tant que fan de son \u00e9quipe actuelle qui a perdu un rookie la semaine derni\u00e8re \u00e0 cause d&#39;une conduite en \u00e9tat d&#39;ivresse, je suis en col\u00e8re.<\/p>\n<p>\u2014 Jason (@_jason_777) <a rel=\"nofollow\" href=\"https:\/\/twitter.com\/_jason_777\/status\/1812632768779837635?ref_src=twsrc%5Etfw\">14 juillet 2024<\/a><\/p>\n<\/blockquote>\n<p>L&#39;arrestation d&#39;Addison est une distraction dont l&#39;\u00e9quipe n&#39;a pas besoin si pr\u00e8s du d\u00e9but du camp d&#39;entra\u00eenement. Les recrues se pr\u00e9senteront au camp le 21 juillet et les v\u00e9t\u00e9rans le 23 juillet. Le talentueux receveur devra faire face \u00e0 des r\u00e9percussions juridiques en raison de sa conduite en \u00e9tat d&#39;ivresse pr\u00e9sum\u00e9e. Le Minnesota esp\u00e8re que ces distractions hors du terrain n&#39;affecteront pas le jeu d&#39;Addison la saison prochaine.<\/p>\n<\/p><\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il a \u00e9t\u00e9 arr\u00eat\u00e9 \u00e0 23h36 HNE et a \u00e9t\u00e9 lib\u00e9r\u00e9 samedi \u00e0 1h36 HNE. La limite l\u00e9gale pour conduire en Californie est de 0,08.<\/p>\n","protected":false},"author":1,"featured_media":11034,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[5777,2684,1236,2317,12,776,3189,5780,5779,51,1301,5778,1875,2278],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le WR des Vikings Jordan Addison a \u00e9t\u00e9 arr\u00eat\u00e9 vendredi dernier pour suspicion de conduite sous l&#039;emprise de l&#039;alcool<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le WR des Vikings Jordan Addison a \u00e9t\u00e9 arr\u00eat\u00e9 vendredi dernier pour suspicion de conduite sous l&#039;emprise de l&#039;alcool\" \/>\n<meta property=\"og:description\" content=\"Il a \u00e9t\u00e9 arr\u00eat\u00e9 \u00e0 23h36 HNE et a \u00e9t\u00e9 lib\u00e9r\u00e9 samedi \u00e0 1h36 HNE. La limite l\u00e9gale pour conduire en Californie est de 0,08.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/\" \/>\n<meta property=\"og:site_name\" content=\"Foot d&#039;avant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Footdavant\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-15T18:48:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-15T18:48:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/07\/Le-WR-des-Vikings-Jordan-Addison-a-ete-arrete-vendredi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"464\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:site\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/\"},\"author\":{\"name\":\"Cl\u00e9ment\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\"},\"headline\":\"Le WR des Vikings Jordan Addison a \u00e9t\u00e9 arr\u00eat\u00e9 vendredi dernier pour suspicion de conduite sous l&#39;emprise de l&#39;alcool\",\"datePublished\":\"2024-07-15T18:48:27+00:00\",\"dateModified\":\"2024-07-15T18:48:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/\"},\"wordCount\":554,\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"keywords\":[\"Addison\",\"arr\u00eat\u00e9\",\"conduite\",\"dernier\",\"des\",\"\u00e9t\u00e9\",\"Jordan\",\"l39alcool\",\"l39emprise\",\"pour\",\"sous\",\"suspicion\",\"vendredi\",\"Vikings\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/\",\"name\":\"Le WR des Vikings Jordan Addison a \u00e9t\u00e9 arr\u00eat\u00e9 vendredi dernier pour suspicion de conduite sous l&#39;emprise de l&#39;alcool\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\"},\"datePublished\":\"2024-07-15T18:48:27+00:00\",\"dateModified\":\"2024-07-15T18:48:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/footdavant.fr\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le WR des Vikings Jordan Addison a \u00e9t\u00e9 arr\u00eat\u00e9 vendredi dernier pour suspicion de conduite sous l&#39;emprise de l&#39;alcool\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"name\":\"Foot d'avant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\",\"name\":\"Foot d'avant\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"contentUrl\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"width\":936,\"height\":549,\"caption\":\"Foot d'avant\"},\"image\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Footdavant\/\",\"https:\/\/twitter.com\/FootdavantFr\",\"https:\/\/www.instagram.com\/footdavant.fr\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\",\"name\":\"Cl\u00e9ment\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9ment\"},\"sameAs\":[\"https:\/\/footdavant.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le WR des Vikings Jordan Addison a \u00e9t\u00e9 arr\u00eat\u00e9 vendredi dernier pour suspicion de conduite sous l&#39;emprise de l&#39;alcool","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/","og_locale":"fr_FR","og_type":"article","og_title":"Le WR des Vikings Jordan Addison a \u00e9t\u00e9 arr\u00eat\u00e9 vendredi dernier pour suspicion de conduite sous l&#39;emprise de l&#39;alcool","og_description":"Il a \u00e9t\u00e9 arr\u00eat\u00e9 \u00e0 23h36 HNE et a \u00e9t\u00e9 lib\u00e9r\u00e9 samedi \u00e0 1h36 HNE. La limite l\u00e9gale pour conduire en Californie est de 0,08.","og_url":"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/","og_site_name":"Foot d&#039;avant","article_publisher":"https:\/\/www.facebook.com\/Footdavant\/","article_published_time":"2024-07-15T18:48:27+00:00","article_modified_time":"2024-07-15T18:48:28+00:00","og_image":[{"width":696,"height":464,"url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/07\/Le-WR-des-Vikings-Jordan-Addison-a-ete-arrete-vendredi.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9ment","twitter_card":"summary_large_image","twitter_creator":"@FootdavantFr","twitter_site":"@FootdavantFr","twitter_misc":{"\u00c9crit par":"Cl\u00e9ment","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/#article","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/"},"author":{"name":"Cl\u00e9ment","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d"},"headline":"Le WR des Vikings Jordan Addison a \u00e9t\u00e9 arr\u00eat\u00e9 vendredi dernier pour suspicion de conduite sous l&#39;emprise de l&#39;alcool","datePublished":"2024-07-15T18:48:27+00:00","dateModified":"2024-07-15T18:48:28+00:00","mainEntityOfPage":{"@id":"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/"},"wordCount":554,"publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"keywords":["Addison","arr\u00eat\u00e9","conduite","dernier","des","\u00e9t\u00e9","Jordan","l39alcool","l39emprise","pour","sous","suspicion","vendredi","Vikings"],"articleSection":["Football"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/","url":"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/","name":"Le WR des Vikings Jordan Addison a \u00e9t\u00e9 arr\u00eat\u00e9 vendredi dernier pour suspicion de conduite sous l&#39;emprise de l&#39;alcool","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/#website"},"datePublished":"2024-07-15T18:48:27+00:00","dateModified":"2024-07-15T18:48:28+00:00","breadcrumb":{"@id":"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/footdavant.fr\/actualites\/le-wr-des-vikings-jordan-addison-a-ete-arrete-vendredi-dernier-pour-suspicion-de-conduite-sous-lemprise-de-lalcool\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/footdavant.fr\/actualites\/"},{"@type":"ListItem","position":2,"name":"Le WR des Vikings Jordan Addison a \u00e9t\u00e9 arr\u00eat\u00e9 vendredi dernier pour suspicion de conduite sous l&#39;emprise de l&#39;alcool"}]},{"@type":"WebSite","@id":"https:\/\/footdavant.fr\/actualites\/#website","url":"https:\/\/footdavant.fr\/actualites\/","name":"Foot d'avant","description":"","publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/footdavant.fr\/actualites\/#organization","name":"Foot d'avant","url":"https:\/\/footdavant.fr\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","contentUrl":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","width":936,"height":549,"caption":"Foot d'avant"},"image":{"@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Footdavant\/","https:\/\/twitter.com\/FootdavantFr","https:\/\/www.instagram.com\/footdavant.fr\/"]},{"@type":"Person","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d","name":"Cl\u00e9ment","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","caption":"Cl\u00e9ment"},"sameAs":["https:\/\/footdavant.fr\/"]}]}},"_links":{"self":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/11033"}],"collection":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/comments?post=11033"}],"version-history":[{"count":1,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/11033\/revisions"}],"predecessor-version":[{"id":11035,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/11033\/revisions\/11035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media\/11034"}],"wp:attachment":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media?parent=11033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/categories?post=11033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/tags?post=11033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}