{"id":13892,"date":"2024-09-24T09:51:51","date_gmt":"2024-09-24T07:51:51","guid":{"rendered":"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/"},"modified":"2024-09-24T09:51:54","modified_gmt":"2024-09-24T07:51:54","slug":"ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25","status":"publish","type":"post","link":"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/","title":{"rendered":"Ronaldo, Messi : la liste des meilleurs buteurs de tous les temps de la Ligue des champions avant le coup d&#39;envoi de la saison 2024-25"},"content":{"rendered":"<p>Sports Mole examine les 10 meilleurs buteurs de l&#39;histoire de la Ligue des champions et les cinq meilleurs buteurs participant \u00e0 la comp\u00e9tition de cette saison.<\/p>\n<div id=\"article_body\" itemprop=\"articleBody\">\n<p class=\"firstPara\">Le <strong class=\"autotag\">Ligue des Champions<\/strong> pr\u00e9sente les meilleures \u00e9quipes et joueurs d&#39;Europe, et certains des plus beaux buts du football ont \u00e9t\u00e9 marqu\u00e9s dans la principale comp\u00e9tition de clubs de l&#39;UEFA.<\/p>\n<p><strong class=\"autotag\">Cristiano Ronaldo<\/strong> Il est en t\u00eate du classement des buteurs du tournoi, ayant marqu\u00e9 141 fois en 187 apparitions pour le Sporting Lisbonne, Manchester United, le Real Madrid et la Juventus.<\/p>\n<p><strong class=\"autotag\">Lionel Messi<\/strong> est le concurrent le plus proche de Ronaldo, avec 129 buts en 163 apparitions, m\u00eame s&#39;il n&#39;\u00e9galera probablement jamais le total du Portugais \u00e9tant donn\u00e9 qu&#39;il joue en MLS pour l&#39;Inter Miami.<\/p>\n<p>Aucun autre joueur dans l&#39;histoire de la comp\u00e9tition n&#39;a atteint la barre des 100 buts, m\u00eame si Barcelone <strong class=\"autotag\">Robert Lewandowski<\/strong> a marqu\u00e9 \u00e0 94 reprises.<\/p>\n<p class=\"imgI\">\n<p><strong class=\"autotag\">Karim Benzema<\/strong> est le seul autre joueur \u00e0 avoir marqu\u00e9 au moins 90 fois, et il y a un \u00e9cart consid\u00e9rable entre le Fran\u00e7ais et le cinqui\u00e8me <strong class=\"autotag\">Ra\u00fal Gonz\u00e1lez<\/strong>qui a marqu\u00e9 71 fois.<\/p>\n<p>Les seuls joueurs du top 20 qui participeront \u00e0 l&#39;\u00e9dition 2024-25 de la Ligue des champions sont Lewandowski, <strong class=\"autotag\">Thomas M\u00fcller<\/strong>, <strong class=\"autotag\">Kylian Mbapp\u00e9<\/strong>, <strong class=\"autotag\">Mohamed Salah<\/strong> et <strong class=\"autotag\">Erling Haaland<\/strong>.<\/p>\n<p>Le total de 41 buts de Haaland est particuli\u00e8rement impressionnant si l&#39;on consid\u00e8re qu&#39;il a accumul\u00e9 ce total en seulement 39 matchs.<\/p>\n<p>Ici, <strong>Taupe sportive<\/strong> pr\u00e9sente les 10 meilleurs buteurs de l&#39;histoire de la Ligue des champions, ainsi que les cinq meilleurs buteurs qui participeront \u00e0 la comp\u00e9tition de cette saison.<\/p>\n<hr>\n<p><\/p>\n<h2>1. Cristiano Ronaldo (141 buts)<\/h2>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 141<\/p>\n<p><strong>Apparitions<\/strong>: 187<\/p>\n<p><strong>Rapport<\/strong>: 0,75 but par match<\/p>\n<p><strong>Aides<\/strong>: 42<\/p>\n<p><strong>Contributions globales \u00e0 l&#39;objectif<\/strong>:183 (0,98 par match)<\/p>\n<p><strong>Ann\u00e9es d&#39;activit\u00e9<\/strong>: 2002-pr\u00e9sent<\/p>\n<p><strong>Clubs de la Ligue des Champions<\/strong>:<br \/>Sporting Lisbonne (0 but en 2 matchs)<br \/>Manchester United (22 buts en 61 matchs)<br \/>Real Madrid (105 buts 102 matchs)<br \/>Juventus (14 buts en 23 matchs)<\/p>\n<p><strong>La saison la plus prolifique<\/strong>:17 buts (11 matchs, 2013-14)<\/p>\n<p><strong>Premier but<\/strong>: 9 ao\u00fbt 2005 (contre Debrecen)<\/p>\n<p><strong>Dernier but<\/strong>:23 novembre 2021 (contre Villarreal)<\/p>\n<hr>\n<p><\/p>\n<h2>2. Lionel Messi (129 buts)<\/h2>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 129<\/p>\n<p><strong>Apparitions<\/strong>: 163<\/p>\n<p><strong>Rapport<\/strong>: 0,79 but par match<\/p>\n<p><strong>Aides<\/strong>: 40<\/p>\n<p><strong>Contributions globales \u00e0 l&#39;objectif<\/strong>: 169 (1,04 par match)<\/p>\n<p><strong>Ann\u00e9es d&#39;activit\u00e9<\/strong>: 2004-pr\u00e9sent<\/p>\n<p><strong>Clubs de la Ligue des Champions<\/strong>:<br \/>Barcelone (120 buts en 149 matchs)<br \/>Paris Saint-Germain (9 buts en 14 matchs)<\/p>\n<p><strong>La saison la plus prolifique<\/strong>:14 buts (11 matchs, 2011-12)<\/p>\n<p><strong>Premier but<\/strong>:11 f\u00e9vrier 2005 (contre Panathinaikos)<\/p>\n<p><strong>Dernier but<\/strong>:25 octobre 2022 (contre Maccabi Ha\u00effa)<\/p>\n<hr>\n<p><\/p>\n<h2>3. Robert Lewandowski (94 buts)<\/h2>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 94<\/p>\n<p><strong>Apparitions<\/strong>: 120<\/p>\n<p><strong>Rapport<\/strong>: 0,78 but par match<\/p>\n<p><strong>Aides<\/strong>: 21<\/p>\n<p><strong>Contributions globales \u00e0 l&#39;objectif<\/strong>: 115 (0,96 par match)<\/p>\n<p><strong>Ann\u00e9es d&#39;activit\u00e9<\/strong>: 2007-pr\u00e9sent<\/p>\n<p><strong>Clubs de la Ligue des Champions<\/strong>:<br \/>Borussia Dortmund (17 buts en 28 matchs)<br \/>Bayern Munich (69 buts en 78 matchs)<br \/>Barcelone (8 buts en 14 matchs)<\/p>\n<p><strong>La saison la plus prolifique<\/strong>:15 buts (10 matchs, 2019-20)<\/p>\n<p><strong>Premier but<\/strong>:19 octobre 2011 (contre Olympiacos)<\/p>\n<p><strong>Dernier but<\/strong>:19 septembre 2023 (contre Royal Antwerp)<\/p>\n<hr>\n<p><\/p>\n<h2>4. Karim Benzema (90 buts)<\/h2>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 90<\/p>\n<p><strong>Apparitions<\/strong>: 152<\/p>\n<p><strong>Rapport<\/strong>: 0,59 but par match<\/p>\n<p><strong>Aides<\/strong>: 28<\/p>\n<p><strong>Contributions globales \u00e0 l&#39;objectif<\/strong>: 118 (0,78 par match)<\/p>\n<p><strong>Ann\u00e9es d&#39;activit\u00e9<\/strong>: 2004-pr\u00e9sent<\/p>\n<p><strong>Clubs de la Ligue des Champions<\/strong>:<br \/>Lyon (12 buts en 19 matchs)<br \/>Real Madrid (78 buts en 133 matchs)<\/p>\n<p><strong>La saison la plus prolifique<\/strong>:15 buts (12 matchs, 2021-22)<\/p>\n<p><strong>Premier but<\/strong>: 6 d\u00e9cembre 2005 (contre Rosenborg)<\/p>\n<p><strong>Dernier but<\/strong>:12 avril 2023 (contre Chelsea)<\/p>\n<hr>\n<p><\/p>\n<h2>5. Ra\u00fal Gonzalez (71 buts)<\/h2>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 71<\/p>\n<p><strong>Apparitions<\/strong>: 139<\/p>\n<p><strong>Rapport<\/strong>: 0,51 but par match<\/p>\n<p><strong>Aides<\/strong>: 23<\/p>\n<p><strong>Contributions globales \u00e0 l&#39;objectif<\/strong>: 94 (0,68 par match)<\/p>\n<p><strong>Ann\u00e9es d&#39;activit\u00e9<\/strong>:1994-2015<\/p>\n<p><strong>Clubs de la Ligue des Champions<\/strong>:<br \/>Real Madrid (66 buts en 127 matchs)<br \/>Schalke (5 buts en 12 matchs)<\/p>\n<p><strong>La saison la plus prolifique<\/strong>:10 buts (15 matchs, 1999-00)<\/p>\n<p><strong>Premier but<\/strong>:18 octobre 1995 (contre Ferencvaros)<\/p>\n<p><strong>Dernier but<\/strong>:13 avril 2011 (contre l&#39;Inter Milan)<\/p>\n<hr>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 60<\/p>\n<p><strong>Apparitions<\/strong>: 81<\/p>\n<p><strong>Rapport<\/strong>: 0,74 but par match<\/p>\n<p><strong>Aides<\/strong>: 18<\/p>\n<p><strong>Contributions globales \u00e0 l&#39;objectif<\/strong>: 78 (0,96 par match)<\/p>\n<p><strong>Ann\u00e9es d&#39;activit\u00e9<\/strong>:1998-2012<\/p>\n<p><strong>Clubs de la Ligue des Champions<\/strong>:<br \/>PSV Eindhoven (9 buts en 15 matchs)<br \/>Manchester United (38 buts en 47 matchs)<br \/>Real Madrid (13 buts en 19 matchs)<\/p>\n<p><strong>La saison la plus prolifique<\/strong>:12 buts (9 matchs, 2002-03)<\/p>\n<p><strong>Premier but<\/strong>: 26 ao\u00fbt 1998 (contre NK Maribor)<\/p>\n<p><strong>Dernier but<\/strong>:21 octobre 2008 (contre la Juventus)<\/p>\n<hr>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 59<\/p>\n<p><strong>Apparitions<\/strong>: 112<\/p>\n<p><strong>Rapport<\/strong>: 0,53 but par match<\/p>\n<p><strong>Aides<\/strong>: 25<\/p>\n<p><strong>Contributions globales \u00e0 l&#39;objectif<\/strong>:84 (0,75 par match)<\/p>\n<p><strong>Ann\u00e9es d&#39;activit\u00e9<\/strong>:1992-2012<\/p>\n<p><strong>Clubs de la Ligue des Champions<\/strong>:<br \/>Dynamo Kyiv (22 buts en 35 matchs)<br \/>AC Milan (33 buts en 62 matchs)<br \/>Chelsea (4 buts en 15 matchs)<\/p>\n<p><strong>La saison la plus prolifique<\/strong>:9 buts (12 matchs, 2005-06)<\/p>\n<p><strong>Premier but<\/strong>:7 d\u00e9cembre 1994 (contre le Bayern Munich)<\/p>\n<p><strong>Dernier but<\/strong>:25 ao\u00fbt 2010 (contre Ajax)<\/p>\n<hr>\n<p><\/p>\n<h2>8. Thomas M\u00fcller (54 buts)<\/h2>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 54<\/p>\n<p><strong>Apparitions<\/strong>: 153<\/p>\n<p><strong>Rapport<\/strong>: 0,35 but par match<\/p>\n<p><strong>Aides<\/strong>: 34<\/p>\n<p><strong>Contributions globales \u00e0 l&#39;objectif<\/strong>:88 (0,58 par match)<\/p>\n<p><strong>Ann\u00e9es d&#39;activit\u00e9<\/strong>: 2006-pr\u00e9sent<\/p>\n<p><strong>Clubs de la Ligue des Champions<\/strong>:<br \/>Bayern Munich (54 buts en 153 matchs)<\/p>\n<p><strong>La saison la plus prolifique<\/strong>: 8 buts (13 matchs, 2012-13) | 8 buts (12 matchs, 2015-16)<\/p>\n<p><strong>Premier but<\/strong>:10 mars 2009 (contre le Sporting Lisbonne)<\/p>\n<p><strong>Dernier but<\/strong>:5 mars 2024 (contre la Lazio)<\/p>\n<hr>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 51<\/p>\n<p><strong>Apparitions<\/strong>: 115<\/p>\n<p><strong>Rapport<\/strong>: 0,44 but par match<\/p>\n<p><strong>Aides<\/strong>: 24<\/p>\n<p>Contributions globales aux buts : 75 (0,65 par match)<\/p>\n<p><strong>Ann\u00e9es d&#39;activit\u00e9<\/strong>:1994-2014<\/p>\n<p><strong>Clubs de la Ligue des Champions<\/strong>:<br \/>Monaco (7 buts en 9 matchs)<br \/>Arsenal (35 buts en 78 matchs)<br \/>Barcelone (9 buts en 28 matchs)<\/p>\n<p><strong>La saison la plus prolifique<\/strong>: 7 buts (12 matchs, 2002-03) | 7 buts (11 matchs, 2001-02) | 7 buts (9 matchs, 1997-98)<\/p>\n<p><strong>Premier but<\/strong>:1er octobre 1997 (contre le Bayer Leverkusen)<\/p>\n<p><strong>Dernier but<\/strong>: 8 avril 2009 (contre le Bayern Munich)<\/p>\n<hr>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 50<\/p>\n<p><strong>Apparitions<\/strong>: 85<\/p>\n<p><strong>Rapport<\/strong>: 0,59 but par match<\/p>\n<p><strong>Aides<\/strong>: 6<\/p>\n<p><strong>Contributions globales \u00e0 l&#39;objectif<\/strong>: 56 (0,66 par match)<\/p>\n<p><strong>Ann\u00e9es d&#39;activit\u00e9<\/strong>:1990-2012<\/p>\n<p><strong>Clubs de la Ligue des Champions<\/strong>:<br \/>Juventus (17 buts en 26 matchs)<br \/>AC Milan (33 buts en 59 matchs)<\/p>\n<p><strong>La saison la plus prolifique<\/strong>:10 buts (14 matchs, 2002-03)<\/p>\n<p><strong>Premier but<\/strong>:17 septembre 1997 (contre Feyenoord)<\/p>\n<p><strong>Dernier but<\/strong>:3 novembre 2010 (contre le Real Madrid)<\/p>\n<hr>\n<p><\/p>\n<h2>Les cinq meilleurs buteurs participant \u00e0 la Ligue des champions 2024-25<\/h2>\n<hr>\n<p><\/p>\n<h2>1. Robert Lewandowski (94 buts)<\/h2>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 94<\/p>\n<hr>\n<p><\/p>\n<h2>2. Thomas M\u00fcller (54 buts)<\/h2>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 54<\/p>\n<hr>\n<p><\/p>\n<h2>3. Kylian Mbapp\u00e9 (48 buts)<\/h2>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 48<\/p>\n<p><strong>Apparitions<\/strong>: 73<\/p>\n<p><strong>Rapport<\/strong>: 0,66 but par match<\/p>\n<p><strong>Aides<\/strong>: 26<\/p>\n<p><strong>Contributions globales \u00e0 l&#39;objectif<\/strong>: 74 (1,01 par match)<\/p>\n<p><strong>Ann\u00e9es d&#39;activit\u00e9<\/strong>: 2015-pr\u00e9sent<\/p>\n<p><strong>Clubs de la Ligue des Champions<\/strong>:<br \/>Monaco (6 buts en 9 matchs)<br \/>Paris Saint-Germain (42 buts en 64 matchs)<\/p>\n<p><strong>La saison la plus prolifique<\/strong>: 8 buts (12 matchs, 2023-24) | 8 buts (10 matchs, 2020-21)<\/p>\n<p><strong>Premier but<\/strong>:21 f\u00e9vrier 2017 (contre Manchester City)<\/p>\n<p><strong>Dernier but<\/strong>:16 avril 2024 (contre Barcelone)<\/p>\n<hr>\n<p><\/p>\n<h2>3. Mohamed Salah (48 buts)<\/h2>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 48<\/p>\n<p><strong>Apparitions<\/strong>: 89<\/p>\n<p><strong>Rapport<\/strong>: 0,54 but par match<\/p>\n<p><strong>Aides<\/strong>: 17<\/p>\n<p><strong>Contributions globales \u00e0 l&#39;objectif<\/strong>: 65 (0,73 par match)<\/p>\n<p><strong>Ann\u00e9es d&#39;activit\u00e9<\/strong>: 2009-pr\u00e9sent<\/p>\n<p><strong>Clubs de la Ligue des Champions<\/strong>:<br \/>B\u00e2le (5 buts en 12 matchs)<br \/>Chelsea (0 but en 2 matchs)<br \/>Roma (1 but en 9 matchs)<br \/>Liverpool (42 buts en 66 matchs)<\/p>\n<p><strong>La saison la plus prolifique<\/strong>:10 buts (13 matchs, 2017-18)<\/p>\n<p><strong>Premier but<\/strong>:6 ao\u00fbt 2013 (contre Maccabi Tel Aviv)<\/p>\n<p><strong>Dernier but<\/strong>:21 f\u00e9vrier 2023 (contre le Real Madrid)<\/p>\n<hr>\n<p><\/p>\n<h2>5. Erling Haaland (41 buts)<\/h2>\n<p class=\"imgI\">\n<p><strong>Objectifs<\/strong>: 41<\/p>\n<p><strong>Apparitions<\/strong>: 39<\/p>\n<p><strong>Rapport<\/strong>:1,05 but par match<\/p>\n<p><strong>Aides<\/strong>: 5<\/p>\n<p><strong>Contributions globales \u00e0 l&#39;objectif<\/strong>: 46 (1,18 par match)<\/p>\n<p><strong>Ann\u00e9es d&#39;activit\u00e9<\/strong>: 2016-pr\u00e9sent<\/p>\n<p><strong>Clubs de la Ligue des Champions<\/strong>:<br \/>RB Salzbourg (8 buts en 6 matchs)<br \/>Borussia Dortmund (15 buts en 13 matchs)<br \/>Manchester City (18 buts en 20 matchs)<\/p>\n<p><strong>La saison la plus prolifique<\/strong>:12 buts (11 matchs, 2022-23)<\/p>\n<p><strong>Premier but<\/strong>: 17 septembre 2019 (contre KRC Genk)<\/p>\n<p><strong>Dernier but<\/strong>:6 mars 2024 (contre le FC Copenhague)<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sports Mole examine les 10 meilleurs buteurs de l&#39;histoire de la Ligue des champions et les cinq meilleurs buteurs participant \u00e0 la comp\u00e9tition de cette<\/p>\n","protected":false},"author":1,"featured_media":13893,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[491,4106,31,489,6531,12,93,30,17,219,451,3082,482,168,1338],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ronaldo, Messi : la liste des meilleurs buteurs de tous les temps de la Ligue des champions avant le coup d&#039;envoi de la saison 2024-25<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ronaldo, Messi : la liste des meilleurs buteurs de tous les temps de la Ligue des champions avant le coup d&#039;envoi de la saison 2024-25\" \/>\n<meta property=\"og:description\" content=\"Sports Mole examine les 10 meilleurs buteurs de l&#039;histoire de la Ligue des champions et les cinq meilleurs buteurs participant \u00e0 la comp\u00e9tition de cette\" \/>\n<meta property=\"og:url\" content=\"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/\" \/>\n<meta property=\"og:site_name\" content=\"Foot d&#039;avant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Footdavant\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-24T07:51:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-24T07:51:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/09\/Ronaldo-Messi-la-liste-des-meilleurs-buteurs-de-tous.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:site\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/\"},\"author\":{\"name\":\"Cl\u00e9ment\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\"},\"headline\":\"Ronaldo, Messi : la liste des meilleurs buteurs de tous les temps de la Ligue des champions avant le coup d&#39;envoi de la saison 2024-25\",\"datePublished\":\"2024-09-24T07:51:51+00:00\",\"dateModified\":\"2024-09-24T07:51:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/\"},\"wordCount\":1100,\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"keywords\":[\"avant\",\"buteurs\",\"champions\",\"coup\",\"d39envoi\",\"des\",\"les\",\"Ligue\",\"liste\",\"meilleurs\",\"Messi\",\"Ronaldo\",\"saison\",\"temps\",\"Tous\"],\"articleSection\":[\"Champions League\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/\",\"name\":\"Ronaldo, Messi : la liste des meilleurs buteurs de tous les temps de la Ligue des champions avant le coup d&#39;envoi de la saison 2024-25\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\"},\"datePublished\":\"2024-09-24T07:51:51+00:00\",\"dateModified\":\"2024-09-24T07:51:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/footdavant.fr\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ronaldo, Messi : la liste des meilleurs buteurs de tous les temps de la Ligue des champions avant le coup d&#39;envoi de la saison 2024-25\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"name\":\"Foot d'avant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\",\"name\":\"Foot d'avant\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"contentUrl\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"width\":936,\"height\":549,\"caption\":\"Foot d'avant\"},\"image\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Footdavant\/\",\"https:\/\/twitter.com\/FootdavantFr\",\"https:\/\/www.instagram.com\/footdavant.fr\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\",\"name\":\"Cl\u00e9ment\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9ment\"},\"sameAs\":[\"https:\/\/footdavant.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ronaldo, Messi : la liste des meilleurs buteurs de tous les temps de la Ligue des champions avant le coup d&#39;envoi de la saison 2024-25","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/","og_locale":"fr_FR","og_type":"article","og_title":"Ronaldo, Messi : la liste des meilleurs buteurs de tous les temps de la Ligue des champions avant le coup d&#39;envoi de la saison 2024-25","og_description":"Sports Mole examine les 10 meilleurs buteurs de l&#39;histoire de la Ligue des champions et les cinq meilleurs buteurs participant \u00e0 la comp\u00e9tition de cette","og_url":"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/","og_site_name":"Foot d&#039;avant","article_publisher":"https:\/\/www.facebook.com\/Footdavant\/","article_published_time":"2024-09-24T07:51:51+00:00","article_modified_time":"2024-09-24T07:51:54+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/09\/Ronaldo-Messi-la-liste-des-meilleurs-buteurs-de-tous.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9ment","twitter_card":"summary_large_image","twitter_creator":"@FootdavantFr","twitter_site":"@FootdavantFr","twitter_misc":{"\u00c9crit par":"Cl\u00e9ment","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/#article","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/"},"author":{"name":"Cl\u00e9ment","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d"},"headline":"Ronaldo, Messi : la liste des meilleurs buteurs de tous les temps de la Ligue des champions avant le coup d&#39;envoi de la saison 2024-25","datePublished":"2024-09-24T07:51:51+00:00","dateModified":"2024-09-24T07:51:54+00:00","mainEntityOfPage":{"@id":"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/"},"wordCount":1100,"publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"keywords":["avant","buteurs","champions","coup","d39envoi","des","les","Ligue","liste","meilleurs","Messi","Ronaldo","saison","temps","Tous"],"articleSection":["Champions League"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/","url":"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/","name":"Ronaldo, Messi : la liste des meilleurs buteurs de tous les temps de la Ligue des champions avant le coup d&#39;envoi de la saison 2024-25","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/#website"},"datePublished":"2024-09-24T07:51:51+00:00","dateModified":"2024-09-24T07:51:54+00:00","breadcrumb":{"@id":"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/footdavant.fr\/actualites\/ronaldo-messi-la-liste-des-meilleurs-buteurs-de-tous-les-temps-de-la-ligue-des-champions-avant-le-coup-denvoi-de-la-saison-2024-25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/footdavant.fr\/actualites\/"},{"@type":"ListItem","position":2,"name":"Ronaldo, Messi : la liste des meilleurs buteurs de tous les temps de la Ligue des champions avant le coup d&#39;envoi de la saison 2024-25"}]},{"@type":"WebSite","@id":"https:\/\/footdavant.fr\/actualites\/#website","url":"https:\/\/footdavant.fr\/actualites\/","name":"Foot d'avant","description":"","publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/footdavant.fr\/actualites\/#organization","name":"Foot d'avant","url":"https:\/\/footdavant.fr\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","contentUrl":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","width":936,"height":549,"caption":"Foot d'avant"},"image":{"@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Footdavant\/","https:\/\/twitter.com\/FootdavantFr","https:\/\/www.instagram.com\/footdavant.fr\/"]},{"@type":"Person","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d","name":"Cl\u00e9ment","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","caption":"Cl\u00e9ment"},"sameAs":["https:\/\/footdavant.fr\/"]}]}},"_links":{"self":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/13892"}],"collection":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/comments?post=13892"}],"version-history":[{"count":1,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/13892\/revisions"}],"predecessor-version":[{"id":13894,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/13892\/revisions\/13894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media\/13893"}],"wp:attachment":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media?parent=13892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/categories?post=13892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/tags?post=13892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}