{"id":19182,"date":"2025-01-26T13:48:40","date_gmt":"2025-01-26T12:48:40","guid":{"rendered":"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/"},"modified":"2025-01-26T13:48:43","modified_gmt":"2025-01-26T12:48:43","slug":"mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb","status":"publish","type":"post","link":"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/","title":{"rendered":"Mikel Arteta explique l&#39;absence de Myles Lewis-Skelly de la confusion de la Ligue des champions d&#39;Arsenal avec Dinamo Zagreb"},"content":{"rendered":"<p>L&#39;entra\u00eeneur-chef d&#39;Arsenal, Mikel Arteta, explique la raison de l&#39;absence de Myles Lewis-Skelly de l&#39;\u00e9quipe des Gunners pour affronter Dinamo Zagreb en Ligue des champions.<\/p>\n<div id=\"article_body\" itemprop=\"articleBody\">\n<h3 class=\"firstPara\">\n<strong class=\"autotag\">Arsenal<\/strong> directeur <strong class=\"autotag\">Mikel Arteta<\/strong> a confirm\u00e9 que <strong class=\"autotag\">Myles Lewis-Skelly<\/strong> est absent de mercredi <strong class=\"autotag\">Ligue des champions<\/strong> jouer contre <strong class=\"autotag\">Dinamo zagreb<\/strong> en raison d&#39;une blessure.<\/h3>\n<p>Le joueur de 18 ans \u00e9tait une omission inattendue de l&#39;\u00e9quipe pour affronter les g\u00e9ants croates des Emirats apr\u00e8s avoir termin\u00e9 les 90 minutes compl\u00e8tes de samedi <strong>2-2-2 Premier League avec Aston Villa<\/strong>.<\/p>\n<p>Plut\u00f4t, <strong class=\"autotag\">Oleksandr Zinchenko<\/strong> Fait une apparition rare \u00e0 l&#39;arri\u00e8re gauche sur Lewis-Skelly, qui a fait commencer sa premi\u00e8re Ligue des champions <strong>La victoire 3-0 d&#39;Arsenal sur Monaco<\/strong> Pendant le tour pr\u00e9c\u00e9dent.<\/p>\n<p>Parler \u00e0 <em>TNT Sports<\/em> Avant le coup d&#39;envoi, Arteta a confirm\u00e9 que Lewis-Skelly avait \u00e9t\u00e9 impliqu\u00e9 dans \u00ab\u00a0un incident\u00a0\u00bb lors de l&#39;affrontement de haut vol avec les Lions, d&#39;o\u00f9 son omission de l&#39;\u00e9quipe de match mercredi.<\/p>\n<p>Cependant, le patron des Gunners n&#39;a pas dit \u00e0 quel point le probl\u00e8me de l&#39;adolescent \u00e9tait grave, r\u00e9pondant: \u00ab\u00a0Il n&#39;a pas pu terminer la s\u00e9ance d&#39;entra\u00eenement malheureusement. Il a eu un incident pendant le match contre Villa et il ne se sentait pas juste hier.\u00a0\u00bb<\/p>\n<p>Alors qu&#39;un arri\u00e8re gauche \u00e0 Lewis-Skelly est entr\u00e9 dans la salle de traitement, Arteta a maintenant <strong class=\"autotag\">Riccardo Calafiori<\/strong> Disponible \u00e0 nouveau apr\u00e8s que l&#39;international italien a rat\u00e9 trois matchs avec une blessure musculaire.<\/p>\n<h2 class=\"k3\">Arteta apporte quatre changements pour la confrontation de Dinamo Zagreb<\/h2>\n<p class=\"imgI\">\n<p>L&#39;international italien n&#39;est que parmi les substituts, cependant, comme c&#39;est <strong class=\"autotag\">Ethan Nwaneri<\/strong> Suite \u00e0 sa propre pr\u00e9occupation musculaire, et Arteta a r\u00e9v\u00e9l\u00e9 que le premier n&#39;\u00e9tait pas en mesure de voir mardi la session d&#39;entra\u00eenement compl\u00e8te.<\/p>\n<p>\u00ab\u00a0La m\u00eame chose avec Riccy aussi, il ne s&#39;est form\u00e9 que 20 minutes hier\u00a0\u00bb, a ajout\u00e9 Arteta. \u00ab\u00a0Alors adaptez \u00e0 nouveau comme nous l&#39;avons fait toute la saison et que nous avons de la fra\u00eecheur dans l&#39;\u00e9quipe, ce qui, je pense, est \u00e9galement important.\u00a0\u00bb<\/p>\n<p>Zinchenko n&#39;est pas le seul d\u00e9marreur rare de la ligne de fond d&#39;Arsenal, comme <strong class=\"autotag\">Jakub Kiwior<\/strong> a \u00e9t\u00e9 rep\u00each\u00e9 au dos central aux c\u00f4t\u00e9s <strong class=\"autotag\">Gabriel Magalhaes<\/strong>intervenant pour <strong class=\"autotag\">William Saliba<\/strong> tandis que le Fran\u00e7ais recouvre une blessure aux ischio-jambiers.<\/p>\n<p>L&#39;introduction de Kiwior permet \u00e0 Arteta de changer <strong class=\"autotag\">Jurrien Timber<\/strong> \u00e0 l&#39;arri\u00e8re droit \u00e0 la place de <strong class=\"autotag\">Thomas Partey<\/strong>qui est r\u00e9trograd\u00e9 sur le banc comme <strong class=\"autotag\">Jorginho<\/strong> vient \u00e0 c\u00f4t\u00e9 <strong class=\"autotag\">Declan Rice<\/strong> et <strong class=\"autotag\">Martin Odegaard<\/strong> au milieu de terrain.<\/p>\n<p>Le patron des Gunners a \u00e9galement fait un changement \u00e0 l&#39;avance, faisant la promotion <strong class=\"autotag\">Raheem Sterling<\/strong> Retour au premier xi sur le c\u00f4t\u00e9 droit comme <strong class=\"autotag\">Leandro Trossard<\/strong> Fait la place, malgr\u00e9 la paire de passes d\u00e9cisives de la Belge ce week-end.<\/p>\n<p>Arsenal est d\u00e9j\u00e0 assur\u00e9 d&#39;un lieu de s\u00e9ries \u00e9liminatoires en Ligue des champions, et la victoire ce soir assurerait pratiquement aux hommes d&#39;Arteta d&#39;une finition sup\u00e9rieure et une place dans les 16 derniers sans avoir besoin de s\u00e9ries \u00e9liminatoires \u00e0 deux pattes.<\/p>\n<p>Les Gunners ont remport\u00e9 leurs trois matchs \u00e0 domicile de la Ligue des champions sans conc\u00e9der jusqu&#39;\u00e0 pr\u00e9sent cette saison et <strong>pourrait d&#39;abord r\u00e9aliser un club<\/strong> en battant <strong class=\"autotag\">Fabio Cannavaro<\/strong>Le c\u00f4t\u00e9 de la capitale anglaise ce soir.<\/p>\n<div class=\"author_box\">\n<div class=\"author_box_banner\">\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&#39;entra\u00eeneur-chef d&#39;Arsenal, Mikel Arteta, explique la raison de l&#39;absence de Myles Lewis-Skelly de l&#39;\u00e9quipe des Gunners pour affronter Dinamo Zagreb en Ligue des champions. Arsenal<\/p>\n","protected":false},"author":1,"featured_media":19183,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[211,91,31,4534,4221,12,5682,577,4873,6891,30,210,6919,6131],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mikel Arteta explique l&#039;absence de Myles Lewis-Skelly de la confusion de la Ligue des champions d&#039;Arsenal avec Dinamo Zagreb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mikel Arteta explique l&#039;absence de Myles Lewis-Skelly de la confusion de la Ligue des champions d&#039;Arsenal avec Dinamo Zagreb\" \/>\n<meta property=\"og:description\" content=\"L&#039;entra\u00eeneur-chef d&#039;Arsenal, Mikel Arteta, explique la raison de l&#039;absence de Myles Lewis-Skelly de l&#039;\u00e9quipe des Gunners pour affronter Dinamo Zagreb en Ligue des champions. Arsenal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/\" \/>\n<meta property=\"og:site_name\" content=\"Foot d&#039;avant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Footdavant\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-26T12:48:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-26T12:48:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2025\/01\/1737895721_Mikel-Arteta-explique-l39absence-de-Myles-Lewis-Skelly-de-la-confusion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:site\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/\"},\"author\":{\"name\":\"Cl\u00e9ment\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\"},\"headline\":\"Mikel Arteta explique l&#39;absence de Myles Lewis-Skelly de la confusion de la Ligue des champions d&#39;Arsenal avec Dinamo Zagreb\",\"datePublished\":\"2025-01-26T12:48:40+00:00\",\"dateModified\":\"2025-01-26T12:48:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/\"},\"wordCount\":591,\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"keywords\":[\"Arteta\",\"avec\",\"champions\",\"confusion\",\"d39Arsenal\",\"des\",\"Dinamo\",\"explique\",\"l39absence\",\"LewisSkelly\",\"Ligue\",\"Mikel\",\"Myles\",\"Zagreb\"],\"articleSection\":[\"Champions League\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/\",\"name\":\"Mikel Arteta explique l&#39;absence de Myles Lewis-Skelly de la confusion de la Ligue des champions d&#39;Arsenal avec Dinamo Zagreb\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\"},\"datePublished\":\"2025-01-26T12:48:40+00:00\",\"dateModified\":\"2025-01-26T12:48:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/footdavant.fr\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mikel Arteta explique l&#39;absence de Myles Lewis-Skelly de la confusion de la Ligue des champions d&#39;Arsenal avec Dinamo Zagreb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"name\":\"Foot d'avant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\",\"name\":\"Foot d'avant\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"contentUrl\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"width\":936,\"height\":549,\"caption\":\"Foot d'avant\"},\"image\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Footdavant\/\",\"https:\/\/twitter.com\/FootdavantFr\",\"https:\/\/www.instagram.com\/footdavant.fr\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\",\"name\":\"Cl\u00e9ment\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9ment\"},\"sameAs\":[\"https:\/\/footdavant.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mikel Arteta explique l&#39;absence de Myles Lewis-Skelly de la confusion de la Ligue des champions d&#39;Arsenal avec Dinamo Zagreb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/","og_locale":"fr_FR","og_type":"article","og_title":"Mikel Arteta explique l&#39;absence de Myles Lewis-Skelly de la confusion de la Ligue des champions d&#39;Arsenal avec Dinamo Zagreb","og_description":"L&#39;entra\u00eeneur-chef d&#39;Arsenal, Mikel Arteta, explique la raison de l&#39;absence de Myles Lewis-Skelly de l&#39;\u00e9quipe des Gunners pour affronter Dinamo Zagreb en Ligue des champions. Arsenal","og_url":"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/","og_site_name":"Foot d&#039;avant","article_publisher":"https:\/\/www.facebook.com\/Footdavant\/","article_published_time":"2025-01-26T12:48:40+00:00","article_modified_time":"2025-01-26T12:48:43+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2025\/01\/1737895721_Mikel-Arteta-explique-l39absence-de-Myles-Lewis-Skelly-de-la-confusion.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9ment","twitter_card":"summary_large_image","twitter_creator":"@FootdavantFr","twitter_site":"@FootdavantFr","twitter_misc":{"\u00c9crit par":"Cl\u00e9ment","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/#article","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/"},"author":{"name":"Cl\u00e9ment","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d"},"headline":"Mikel Arteta explique l&#39;absence de Myles Lewis-Skelly de la confusion de la Ligue des champions d&#39;Arsenal avec Dinamo Zagreb","datePublished":"2025-01-26T12:48:40+00:00","dateModified":"2025-01-26T12:48:43+00:00","mainEntityOfPage":{"@id":"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/"},"wordCount":591,"publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"keywords":["Arteta","avec","champions","confusion","d39Arsenal","des","Dinamo","explique","l39absence","LewisSkelly","Ligue","Mikel","Myles","Zagreb"],"articleSection":["Champions League"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/","url":"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/","name":"Mikel Arteta explique l&#39;absence de Myles Lewis-Skelly de la confusion de la Ligue des champions d&#39;Arsenal avec Dinamo Zagreb","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/#website"},"datePublished":"2025-01-26T12:48:40+00:00","dateModified":"2025-01-26T12:48:43+00:00","breadcrumb":{"@id":"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/footdavant.fr\/actualites\/mikel-arteta-explique-labsence-de-myles-lewis-skelly-de-la-confusion-de-la-ligue-des-champions-darsenal-avec-dinamo-zagreb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/footdavant.fr\/actualites\/"},{"@type":"ListItem","position":2,"name":"Mikel Arteta explique l&#39;absence de Myles Lewis-Skelly de la confusion de la Ligue des champions d&#39;Arsenal avec Dinamo Zagreb"}]},{"@type":"WebSite","@id":"https:\/\/footdavant.fr\/actualites\/#website","url":"https:\/\/footdavant.fr\/actualites\/","name":"Foot d'avant","description":"","publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/footdavant.fr\/actualites\/#organization","name":"Foot d'avant","url":"https:\/\/footdavant.fr\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","contentUrl":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","width":936,"height":549,"caption":"Foot d'avant"},"image":{"@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Footdavant\/","https:\/\/twitter.com\/FootdavantFr","https:\/\/www.instagram.com\/footdavant.fr\/"]},{"@type":"Person","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d","name":"Cl\u00e9ment","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","caption":"Cl\u00e9ment"},"sameAs":["https:\/\/footdavant.fr\/"]}]}},"_links":{"self":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/19182"}],"collection":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/comments?post=19182"}],"version-history":[{"count":1,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/19182\/revisions"}],"predecessor-version":[{"id":19184,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/19182\/revisions\/19184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media\/19183"}],"wp:attachment":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media?parent=19182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/categories?post=19182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/tags?post=19182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}