{"id":21163,"date":"2025-03-11T05:48:48","date_gmt":"2025-03-11T04:48:48","guid":{"rendered":"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/"},"modified":"2025-03-11T05:48:51","modified_gmt":"2025-03-11T04:48:51","slug":"apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements","status":"publish","type":"post","link":"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/","title":{"rendered":"Aper\u00e7u: Lille vs Borussia Dortmund &#8211; Pr\u00e9diction, nouvelles d&#39;\u00e9quipe, alignements"},"content":{"rendered":"<p>Sports Mole pr\u00e9visualise le conflit de la Ligue des champions de mercredi entre Lille et le Borussia Dortmund, y compris les pr\u00e9dictions, les nouvelles de l&#39;\u00e9quipe et les alignements possibles.<\/p>\n<div id=\"article_body\" itemprop=\"articleBody\">\n<p class=\"firstPara\">Toujours sur la bonne voie pour un historique <strong class=\"autotag\">Ligue des champions<\/strong> r\u00e9alisation, <strong class=\"autotag\">Lille<\/strong> accueillir <strong class=\"autotag\">Borussia Dortmund<\/strong> Pour la jambe de retour de leur houple de 16 \u00e0 \u00e9galit\u00e9 mercredi.<\/p>\n<p>Les Mastiffs ont la possibilit\u00e9 d&#39;atteindre les quarts de finale pour la premi\u00e8re fois, apr\u00e8s une performance impressionnante lors du match aller mardi dernier.<\/p>\n<h2>Aper\u00e7u de correspondance<\/h2>\n<p class=\"imgI\">\n<p>Pas les avantages les plus \u00e9vidents, mais apr\u00e8s avoir lutt\u00e9 avec un match nul 1-1 \u00e0 Dortmund, Lille a toutes les raisons de croire qu&#39;ils peuvent faire l&#39;histoire, en particulier avec Stade Pierre-Mauroy comme une imposante forteresse dans la comp\u00e9tition europ\u00e9enne.<\/p>\n<p>LOSC poss\u00e8de un formidable record au sol, remportant 10 de ses 12 derniers matchs continentaux (D2), dont trois des quatre sorties en phase de ligue de cette saison, apr\u00e8s avoir devanc\u00e9 Sturm Graz 3-2, stup\u00e9fait les titulaires du Real Madrid 1-0 et d\u00e9mantel\u00e9 Feyenoord 6-1 le jour de la porte, seulement des points de suppression d&#39;un standat 1-1 contre la juventus avant cela.<\/p>\n<p>En fait, la forme impressionnante de Lille sur le sol \u00e0 domicile a jou\u00e9 un r\u00f4le central dans leur qualification automatique pour cette \u00e9tape, contribuant 10 points \u00e0 leur transport total de 16 et garantissant une septi\u00e8me place dans les premiers tours.<\/p>\n<p>Leur force \u00e0 Stade Pierre-Mauroy \u00e9tait \u00e0 nouveau \u00e9vidente \u00e0 la Ligue 1 le week-end, comme <strong class=\"autotag\">Bruno Genesio<\/strong>Le c\u00f4t\u00e9 s&#39;est battu au-del <strong class=\"autotag\">Jonathan David<\/strong> frappant au d\u00e9but de la seconde moiti\u00e9 pour assurer une victoire durement disput\u00e9e.<\/p>\n<p>La victoire de mercredi verrait Lille r\u00e9clamer son tout premier triomphe \u00e0 \u00e9limination directe en Ligue des champions, bien qu&#39;ils devront briser un mod\u00e8le familier, le r\u00e9sultat de la semaine derni\u00e8re marquant le troisi\u00e8me match nul cons\u00e9cutif dans les r\u00e9unions entre ces \u00e9quipes.<\/p>\n<p>Leurs rencontres pr\u00e9c\u00e9dentes sont survenues lors du quatri\u00e8me tour de la Coupe UEFA en 2001-2002, lorsqu&#39;une impasse sans rel\u00e2che en Allemagne a \u00e9t\u00e9 suivie d&#39;un score 1-1 en France, permettant \u00e0 Dortmund de progresser sur les buts \u00e0 l&#39;ext\u00e9rieur.<\/p>\n<p class=\"imgI\">\n<p>Si de beaux objectifs seuls pouvaient garantir la victoire, <strong class=\"autotag\">Karim Adeyemi<\/strong>La demi-volley sublime de la premi\u00e8re \u00e9tape aurait fait le travail, mais \u00e0 la place, <strong class=\"autotag\">Hakon Arnar Haraldsson<\/strong>L&#39;\u00e9galiseur de deuxi\u00e8me mi-temps est parti <strong class=\"autotag\">Niko Kovac<\/strong>Le c\u00f4t\u00e9 est confront\u00e9 \u00e0 une bataille difficile pour atteindre des quarts de finale cons\u00e9cutifs.<\/p>\n<p>Ce d\u00e9fi n&#39;est accroch\u00e9 que par les difficult\u00e9s de BVB en France, o\u00f9 ils n&#39;ont remport\u00e9 que deux de leurs 11 derniers voyages (D2 L6), bien qu&#39;ils puissent prendre le c\u0153ur de leur derni\u00e8re sortie &#8211; une victoire 1-0 au Paris Saint-Germain dernier, qui les a mis en parcours pour un triomphe d&#39;agr\u00e9gat 2-0 avant de tomber au Real Madrid en finale.<\/p>\n<p>Ce succ\u00e8s sur le PSG a amen\u00e9 le record de Die Borussen en liens \u00e0 deux pattes contre les clubs fran\u00e7ais \u00e0 quatre victoires et trois d\u00e9faites, ayant subi une \u00e9limination au cours des trois pr\u00e9c\u00e9dents.<\/p>\n<p>Dortmund esp\u00e8re passer mercredi \u00e0 travers un autre adversaire de ce tel adversaire, avec leur forme \u00e0 l&#39;ext\u00e9rieur dans la comp\u00e9tition de cette saison en offrant des encouragements, remportant trois des cinq matchs (L2), y compris un triomphe commandant 3-0 \u00e0 Sporting Lisbonne dans la jambe d&#39;ouverture de la phase de KO, ce qui, finalement, s&#39;est av\u00e9r\u00e9 d\u00e9cisif.<\/p>\n<p>Cependant, BVB a une statistique ind\u00e9sirable \u00e0 surmonter, ayant \u00e9t\u00e9 \u00e9limin\u00e9e dans sept des huit liens europ\u00e9ens o\u00f9 ils se sont retrouv\u00e9s chez eux lors du match aller, plus r\u00e9cemment contre Liverpool dans les quarts de finale de la Ligue Europa 2015-2016 (1-1 H, 3-4 A).<\/p>\n<p>Ajoutant \u00e0 leur besoin de r\u00e9ponse, Dortmund entre dans le choc de mercredi sur le dos d&#39;une d\u00e9faite d\u00e9cevante 1-0 contre Augsbourg en Bundesliga, prolongeant leur course sans victoire \u00e0 deux matchs apr\u00e8s l&#39;impasse de la semaine derni\u00e8re en France.<\/p>\n<p>Formulaire Lille Champions League:<\/p>\n<p>Formulaire Lille (toutes les comp\u00e9titions):<\/p>\n<p>Borussia Dortmund Champions League Form:<\/p>\n<p>Borussia Dortmund Form (toutes les comp\u00e9titions):<\/p>\n<h2>Nouvelles de l&#39;\u00e9quipe<\/h2>\n<p class=\"imgI\">\n<p>Lille a trois absents confirm\u00e9s pour le coup d&#39;envoi de mercredi, avec <strong class=\"autotag\">Edon Zhegrova<\/strong>, <strong class=\"autotag\">Tiago Santos<\/strong> et <strong class=\"autotag\">Samuel Umtiti<\/strong> tous exclus par une blessure, tandis que <strong class=\"autotag\">Osame Sahraoui<\/strong> est un doute apr\u00e8s avoir rat\u00e9 les quatre derniers matchs avec un probl\u00e8me de hanche.<\/p>\n<p>Ajout \u00e0 leurs probl\u00e8mes de fitness, <strong class=\"autotag\">Mitchel Bakker<\/strong> a \u00e9t\u00e9 contraint \u00e0 la mi-temps contre Montpellier avec un probl\u00e8me de tendon, tandis que <strong class=\"autotag\">Gabriel Gudmundssson<\/strong> a rat\u00e9 le match par la maladie.<\/p>\n<p>Entre-temps, <strong class=\"autotag\">Nabil Bentaleb<\/strong> n&#39;est pas \u00e9ligible \u00e0 figurer pour les Dogues, n&#39;ayant tout simplement pas \u00e9t\u00e9 revenu \u00e0 l&#39;action \u00e0 la mi-f\u00e9vrier apr\u00e8s s&#39;\u00eatre remis d&#39;une crise cardiaque, ce qui signifie qu&#39;il n&#39;a pas respect\u00e9 la date limite d&#39;inscription.<\/p>\n<p>Lille pourrait opter pour une gamme inchang\u00e9e du tirage 1-1 de la semaine derni\u00e8re, bien qu&#39;ils puissent modifier leur forme en d\u00e9ploiement d&#39;un syst\u00e8me 4-3-2-1.<\/p>\n<p>Dortmund <strong class=\"autotag\">Daniel Svensson<\/strong> a subi une blessure au genou lors du match aller qui le gardera \u00e0 l&#39;\u00e9cart pendant plusieurs semaines, rejoignant <strong class=\"autotag\">Felix Nmecha<\/strong> (genou) comme les seuls absents confirm\u00e9s pour les visiteurs.<\/p>\n<p>Entre-temps, <strong class=\"autotag\">Carney Chukwuemeka<\/strong> Reste un doute d\u00fb \u00e0 un probl\u00e8me de cuisse, n&#39;ayant fait que quelques apparitions de substitut que r\u00e9cemment.<\/p>\n<p>Il est peu probable que Kovac apporte des modifications radicales \u00e0 son c\u00f4t\u00e9, avec <strong class=\"autotag\">Serhou Guirassy<\/strong> &#8211; qui m\u00e8ne les palmar\u00e8s des notations de la Ligue des champions avec 10 buts &#8211; devrait mener la ligne \u00e0 nouveau contre son ancien club.<\/p>\n<p><strong>Lille de d\u00e9part possible Lille:<\/strong><br \/>Chevalier; Meunier, Diakite, Ribeiro, Ismaily; Bouaddi, Andre, Mukau; Mbappe, David, Haraldssson<\/p>\n<p><strong>Borussia Dortmund Possible Ligne de d\u00e9part:<\/strong><br \/>Kobel; Ryerson, Can, Schlotterbeck, Bensebaini; Sabitzer, Gross; Adeyemi, Brandt, Bynoe-Gittens; Guirassy<\/p>\n<p class=\"sm_center\">\n<h2 class=\"sm_center\">Nous disons: Lille 2-1 Borussia Dortmund (Lille pour gagner 3-2 sur agr\u00e9gat)<\/h2>\n<p>C&#39;est difficile \u00e0 appeler, \u00e9tant donn\u00e9 le solide record \u00e0 domicile de Lille en Ligue des champions et le pedigree de Dortmund dans la comp\u00e9tition.<\/p>\n<p>Cependant, les visiteurs n&#39;ont pas \u00e9t\u00e9 enti\u00e8rement convaincants ces derniers temps, et bien qu&#39;ils aient tenu le coup sur la route lors du tournoi de cette saison, ils n&#39;ont pas \u00e9t\u00e9 exactement un c\u00f4t\u00e9 difficile \u00e0 d\u00e9composer, subissant deux d\u00e9faites en cinq sorties \u00e0 l&#39;ext\u00e9rieur.<\/p>\n<p>Pour l&#39;analyse des donn\u00e9es des r\u00e9sultats les plus probables, les scores et plus encore pour cette correspondance <strong>Veuillez cliquer ici<\/strong>.<\/p>\n<div class=\"author_box\">\n<div class=\"author_box_banner\">\n<\/div>\n<\/div>\n<h2>Aper\u00e7u par e-mail<\/h2>\n<div>Cliquez ici pour obtenir <strong>Taupe de sport<\/strong>Email quotidien des aper\u00e7us et des pr\u00e9dictions pour chaque jeu majeur!<\/div>\n<p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sports Mole pr\u00e9visualise le conflit de la Ligue des champions de mercredi entre Lille et le Borussia Dortmund, y compris les pr\u00e9dictions, les nouvelles de<\/p>\n","protected":false},"author":1,"featured_media":21164,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[7750,284,96,4628,107,3205,461,3917],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aper\u00e7u: Lille vs Borussia Dortmund - Pr\u00e9diction, nouvelles d&#039;\u00e9quipe, alignements<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aper\u00e7u: Lille vs Borussia Dortmund - Pr\u00e9diction, nouvelles d&#039;\u00e9quipe, alignements\" \/>\n<meta property=\"og:description\" content=\"Sports Mole pr\u00e9visualise le conflit de la Ligue des champions de mercredi entre Lille et le Borussia Dortmund, y compris les pr\u00e9dictions, les nouvelles de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/\" \/>\n<meta property=\"og:site_name\" content=\"Foot d&#039;avant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Footdavant\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-11T04:48:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-11T04:48:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2025\/03\/1741668529_Apercu-Lille-vs-Borussia-Dortmund-Prediction-nouvelles-d39equipe-alignements.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:site\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/\"},\"author\":{\"name\":\"Cl\u00e9ment\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\"},\"headline\":\"Aper\u00e7u: Lille vs Borussia Dortmund &#8211; Pr\u00e9diction, nouvelles d&#39;\u00e9quipe, alignements\",\"datePublished\":\"2025-03-11T04:48:48+00:00\",\"dateModified\":\"2025-03-11T04:48:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/\"},\"wordCount\":1161,\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"keywords\":[\"alignements\",\"Aper\u00e7u\",\"Borussia\",\"d39\u00e9quipe\",\"Dortmund\",\"Lille\",\"Nouvelles\",\"pr\u00e9diction\"],\"articleSection\":[\"Champions League\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/\",\"name\":\"Aper\u00e7u: Lille vs Borussia Dortmund - Pr\u00e9diction, nouvelles d&#39;\u00e9quipe, alignements\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\"},\"datePublished\":\"2025-03-11T04:48:48+00:00\",\"dateModified\":\"2025-03-11T04:48:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/footdavant.fr\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aper\u00e7u: Lille vs Borussia Dortmund &#8211; Pr\u00e9diction, nouvelles d&#39;\u00e9quipe, alignements\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"name\":\"Foot d'avant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\",\"name\":\"Foot d'avant\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"contentUrl\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"width\":936,\"height\":549,\"caption\":\"Foot d'avant\"},\"image\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Footdavant\/\",\"https:\/\/twitter.com\/FootdavantFr\",\"https:\/\/www.instagram.com\/footdavant.fr\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\",\"name\":\"Cl\u00e9ment\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9ment\"},\"sameAs\":[\"https:\/\/footdavant.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aper\u00e7u: Lille vs Borussia Dortmund - Pr\u00e9diction, nouvelles d&#39;\u00e9quipe, alignements","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/","og_locale":"fr_FR","og_type":"article","og_title":"Aper\u00e7u: Lille vs Borussia Dortmund - Pr\u00e9diction, nouvelles d&#39;\u00e9quipe, alignements","og_description":"Sports Mole pr\u00e9visualise le conflit de la Ligue des champions de mercredi entre Lille et le Borussia Dortmund, y compris les pr\u00e9dictions, les nouvelles de","og_url":"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/","og_site_name":"Foot d&#039;avant","article_publisher":"https:\/\/www.facebook.com\/Footdavant\/","article_published_time":"2025-03-11T04:48:48+00:00","article_modified_time":"2025-03-11T04:48:51+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2025\/03\/1741668529_Apercu-Lille-vs-Borussia-Dortmund-Prediction-nouvelles-d39equipe-alignements.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9ment","twitter_card":"summary_large_image","twitter_creator":"@FootdavantFr","twitter_site":"@FootdavantFr","twitter_misc":{"\u00c9crit par":"Cl\u00e9ment","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/#article","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/"},"author":{"name":"Cl\u00e9ment","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d"},"headline":"Aper\u00e7u: Lille vs Borussia Dortmund &#8211; Pr\u00e9diction, nouvelles d&#39;\u00e9quipe, alignements","datePublished":"2025-03-11T04:48:48+00:00","dateModified":"2025-03-11T04:48:51+00:00","mainEntityOfPage":{"@id":"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/"},"wordCount":1161,"publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"keywords":["alignements","Aper\u00e7u","Borussia","d39\u00e9quipe","Dortmund","Lille","Nouvelles","pr\u00e9diction"],"articleSection":["Champions League"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/","url":"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/","name":"Aper\u00e7u: Lille vs Borussia Dortmund - Pr\u00e9diction, nouvelles d&#39;\u00e9quipe, alignements","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/#website"},"datePublished":"2025-03-11T04:48:48+00:00","dateModified":"2025-03-11T04:48:51+00:00","breadcrumb":{"@id":"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/footdavant.fr\/actualites\/apercu-lille-vs-borussia-dortmund-prediction-nouvelles-dequipe-alignements\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/footdavant.fr\/actualites\/"},{"@type":"ListItem","position":2,"name":"Aper\u00e7u: Lille vs Borussia Dortmund &#8211; Pr\u00e9diction, nouvelles d&#39;\u00e9quipe, alignements"}]},{"@type":"WebSite","@id":"https:\/\/footdavant.fr\/actualites\/#website","url":"https:\/\/footdavant.fr\/actualites\/","name":"Foot d'avant","description":"","publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/footdavant.fr\/actualites\/#organization","name":"Foot d'avant","url":"https:\/\/footdavant.fr\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","contentUrl":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","width":936,"height":549,"caption":"Foot d'avant"},"image":{"@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Footdavant\/","https:\/\/twitter.com\/FootdavantFr","https:\/\/www.instagram.com\/footdavant.fr\/"]},{"@type":"Person","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d","name":"Cl\u00e9ment","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","caption":"Cl\u00e9ment"},"sameAs":["https:\/\/footdavant.fr\/"]}]}},"_links":{"self":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/21163"}],"collection":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/comments?post=21163"}],"version-history":[{"count":1,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/21163\/revisions"}],"predecessor-version":[{"id":21165,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/21163\/revisions\/21165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media\/21164"}],"wp:attachment":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media?parent=21163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/categories?post=21163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/tags?post=21163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}