{"id":21207,"date":"2025-03-12T02:48:25","date_gmt":"2025-03-12T01:48:25","guid":{"rendered":"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/"},"modified":"2025-03-12T02:48:26","modified_gmt":"2025-03-12T01:48:26","slug":"man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete","status":"publish","type":"post","link":"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/","title":{"rendered":"Man City, Paris Saint-Germain &#39;To Assy Tire-to-Head&#39; pour le milieu de terrain du Real Madrid de 59 millions de livres sterling cet \u00e9t\u00e9"},"content":{"rendered":"<p>Le Real Madrid aurait fix\u00e9 un prix demand\u00e9 de 59 millions de livres sterling pour Eduardo Camavinga, le Paris Saint-Germain et Manchester City le souhaitaient tous deux.<\/p>\n<div id=\"article_body\" itemprop=\"articleBody\">\n<h3 class=\"firstPara\">\n<strong class=\"autotag\">Real Madrid<\/strong> auraient fix\u00e9 un prix demand\u00e9 de 70 millions d&#39;euros (59 millions de livres sterling) pour <strong class=\"autotag\">Eduardo Camavinga<\/strong>avec <strong class=\"autotag\">Paris Saint-Germain<\/strong> et <strong class=\"autotag\">MANCHESTER CITY<\/strong> tous deux int\u00e9ress\u00e9s \u00e0 signer le milieu de terrain pendant la fen\u00eatre de transfert de cet \u00e9t\u00e9.<\/h3>\n<p>Camavinga, 22 ans, a eu des probl\u00e8mes de blessures au cours de la campagne 2024-25, \u00e9tant limit\u00e9e \u00e0 seulement 24 apparitions toutes comp\u00e9titions, et il y a actuellement des sp\u00e9culations entourant son avenir.<\/p>\n<p>Selon <em>Fichajes<\/em>Le Real Madrid serait dispos\u00e9 \u00e0 laisser l&#39;international de France partir cet \u00e9t\u00e9 pour 70 millions d&#39;euros (59 millions de livres sterling), et PSG et Man City manifestent un int\u00e9r\u00eat pour ses services.<\/p>\n<p>Le rapport affirme qu&#39;il n&#39;y a pas d&#39;offres formelles sur la table \u00e0 ce stade de la proc\u00e9dure, mais il est pr\u00e9vu qu&#39;il sera en mouvement pendant la fen\u00eatre de transfert de cet \u00e9t\u00e9.<\/p>\n<p>Camavinga a d\u00e9m\u00e9nag\u00e9 au Real Madrid depuis Rennes \u00e0 l&#39;\u00e9t\u00e9 2021, et il a repr\u00e9sent\u00e9 Los Blancos \u00e0 170 reprises dans toutes les comp\u00e9titions, marquant trois buts et enregistrant neuf passes d\u00e9cisives dans le processus.<\/p>\n<p class=\"imgI\">\n<h2 class=\"k3\">PSG, Man City \u00abInt\u00e9ress\u00e9 par la camavage du Real Madrid\u00bb<\/h2>\n<p>Entra\u00eeneur-chef du Real Madrid <strong class=\"autotag\">Carlo Ancelotti<\/strong> a \u00e9t\u00e9 interrog\u00e9 sur Camavinga lors de sa conf\u00e9rence de presse samedi pour pr\u00e9visualiser le conflit de Liga avec Rayo Vallecano dimanche apr\u00e8s-midi.<\/p>\n<p>\u00ab\u00a0Il n&#39;a pas eu de continuit\u00e9, il a subi des blessures importantes. Il est absent depuis trois mois et demi, ce qui rend plus difficile la continuit\u00e9\u00a0\u00bb, a d\u00e9clar\u00e9 Ancelotti aux journalistes<\/p>\n<p>\u00ab\u00a0Maintenant, il s&#39;am\u00e9liore petit \u00e0 petit, lors des derniers matchs, il a eu des maux de dos qui ne lui ont pas permis de jouer \u00e0 100%. Il est tenu \u00e0 cause des besoins de l&#39;\u00e9quipe, il sera de retour \u00e0 son meilleur.\u00a0\u00bb<\/p>\n<p>Camavinga a commenc\u00e9 contre l&#39;Atletico Madrid en Ligue des champions la semaine derni\u00e8re, mais il a \u00e9t\u00e9 remplac\u00e9 apr\u00e8s l&#39;heure, et le Fran\u00e7ais \u00e9tait en retard <strong class=\"autotag\">Dani Ceballos<\/strong> dans l&#39;ordre hi\u00e9rarchique avant que ce dernier ne soit une blessure r\u00e9cente.<\/p>\n<p class=\"imgI\"><img decoding=\"async\" loading=\"lazy\" class=\"l\" src=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2025\/03\/1741744105_713_Man-City-Paris-Saint-Germain-39To-Assy-Tire-to-Head39-pour-le-milieu.jpg\" title=\"Eduardo Camavinga de France lors du match de demi-finale de son \u00e9quipe contre l&#39;Espagne, le 9 juillet 2024\" alt=\"Eduardo Camavinga de France lors du match de demi-finale de son \u00e9quipe contre l&#39;Espagne, le 9 juillet 2024\" width=\"640\" height=\"480\"><\/p>\n<h2 class=\"k3\">Quel club gagnera la course pour Camavinga?<\/h2>\n<p>Camavinga \u00e9tait li\u00e9 \u00e0 un d\u00e9m\u00e9nagement en Premier League avant de quitter Rennes, avec <strong class=\"autotag\">Manchester United<\/strong> Dit \u00eatre d&#39;\u00e9normes admirateurs, et un passage \u00e0 l&#39;Angleterre plairait s\u00fbrement au milieu de terrain.<\/p>\n<p>Cependant, le PSG pourrait avoir un avantage en raison de l&#39;int\u00e9r\u00eat pr\u00e9sum\u00e9 du Real Madrid pour <strong class=\"autotag\">Joao Neves<\/strong>.<\/p>\n<p>Los Blancos est cens\u00e9 consid\u00e9rer les neves comme le remplacement parfait pour la camavage, par la possibilit\u00e9 de <strong>Une affaire d&#39;\u00e9change s&#39;ouvrant<\/strong>ce qui signifie que Man City peut jouer au rattrapage en ce qui concerne une affaire d&#39;\u00e9t\u00e9.<\/p>\n<p>Un retour en France est \u00e9galement cens\u00e9 \u00eatre attrayant pour la camavage, en particulier avec cette \u00e9quipe du PSG se r\u00e9v\u00e8le \u00eatre une tenue tr\u00e8s excitante et une potentielle de mettre fin \u00e0 leur attente pour un troph\u00e9e de la Ligue des champions dans un avenir proche.<\/p>\n<div class=\"author_box\">\n<div class=\"author_box_banner\">\n<img decoding=\"async\" class=\"author_img\" src=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2025\/03\/1741744105_30_Man-City-Paris-Saint-Germain-39To-Assy-Tire-to-Head39-pour-le-milieu.jpg\"><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le Real Madrid aurait fix\u00e9 un prix demand\u00e9 de 59 millions de livres sterling pour Eduardo Camavinga, le Paris Saint-Germain et Manchester City le souhaitaient<\/p>\n","protected":false},"author":1,"featured_media":21208,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[8211,8433,775,27,776,115,303,24,441,114,100,51,302,249,116,442,8434],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Man City, Paris Saint-Germain &#039;To Assy Tire-to-Head&#039; pour le milieu de terrain du Real Madrid de 59 millions de livres sterling cet \u00e9t\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Man City, Paris Saint-Germain &#039;To Assy Tire-to-Head&#039; pour le milieu de terrain du Real Madrid de 59 millions de livres sterling cet \u00e9t\u00e9\" \/>\n<meta property=\"og:description\" content=\"Le Real Madrid aurait fix\u00e9 un prix demand\u00e9 de 59 millions de livres sterling pour Eduardo Camavinga, le Paris Saint-Germain et Manchester City le souhaitaient\" \/>\n<meta property=\"og:url\" content=\"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/\" \/>\n<meta property=\"og:site_name\" content=\"Foot d&#039;avant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Footdavant\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-12T01:48:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-12T01:48:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2025\/03\/Man-City-Paris-Saint-Germain-39To-Assy-Tire-to-Head39-pour-le-milieu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:site\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/\"},\"author\":{\"name\":\"Cl\u00e9ment\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\"},\"headline\":\"Man City, Paris Saint-Germain &#39;To Assy Tire-to-Head&#39; pour le milieu de terrain du Real Madrid de 59 millions de livres sterling cet \u00e9t\u00e9\",\"datePublished\":\"2025-03-12T01:48:25+00:00\",\"dateModified\":\"2025-03-12T01:48:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/\"},\"wordCount\":558,\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"keywords\":[\"39To\",\"Assy\",\"cet\",\"City\",\"\u00e9t\u00e9\",\"livres\",\"Madrid\",\"Man\",\"milieu\",\"millions\",\"paris\",\"pour\",\"Real\",\"SaintGermain\",\"sterling\",\"terrain\",\"TiretoHead39\"],\"articleSection\":[\"Premier League\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/\",\"name\":\"Man City, Paris Saint-Germain &#39;To Assy Tire-to-Head&#39; pour le milieu de terrain du Real Madrid de 59 millions de livres sterling cet \u00e9t\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\"},\"datePublished\":\"2025-03-12T01:48:25+00:00\",\"dateModified\":\"2025-03-12T01:48:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/footdavant.fr\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Man City, Paris Saint-Germain &#39;To Assy Tire-to-Head&#39; pour le milieu de terrain du Real Madrid de 59 millions de livres sterling cet \u00e9t\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"name\":\"Foot d'avant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\",\"name\":\"Foot d'avant\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"contentUrl\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"width\":936,\"height\":549,\"caption\":\"Foot d'avant\"},\"image\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Footdavant\/\",\"https:\/\/twitter.com\/FootdavantFr\",\"https:\/\/www.instagram.com\/footdavant.fr\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\",\"name\":\"Cl\u00e9ment\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9ment\"},\"sameAs\":[\"https:\/\/footdavant.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Man City, Paris Saint-Germain &#39;To Assy Tire-to-Head&#39; pour le milieu de terrain du Real Madrid de 59 millions de livres sterling cet \u00e9t\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/","og_locale":"fr_FR","og_type":"article","og_title":"Man City, Paris Saint-Germain &#39;To Assy Tire-to-Head&#39; pour le milieu de terrain du Real Madrid de 59 millions de livres sterling cet \u00e9t\u00e9","og_description":"Le Real Madrid aurait fix\u00e9 un prix demand\u00e9 de 59 millions de livres sterling pour Eduardo Camavinga, le Paris Saint-Germain et Manchester City le souhaitaient","og_url":"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/","og_site_name":"Foot d&#039;avant","article_publisher":"https:\/\/www.facebook.com\/Footdavant\/","article_published_time":"2025-03-12T01:48:25+00:00","article_modified_time":"2025-03-12T01:48:26+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2025\/03\/Man-City-Paris-Saint-Germain-39To-Assy-Tire-to-Head39-pour-le-milieu.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9ment","twitter_card":"summary_large_image","twitter_creator":"@FootdavantFr","twitter_site":"@FootdavantFr","twitter_misc":{"\u00c9crit par":"Cl\u00e9ment","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/#article","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/"},"author":{"name":"Cl\u00e9ment","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d"},"headline":"Man City, Paris Saint-Germain &#39;To Assy Tire-to-Head&#39; pour le milieu de terrain du Real Madrid de 59 millions de livres sterling cet \u00e9t\u00e9","datePublished":"2025-03-12T01:48:25+00:00","dateModified":"2025-03-12T01:48:26+00:00","mainEntityOfPage":{"@id":"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/"},"wordCount":558,"publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"keywords":["39To","Assy","cet","City","\u00e9t\u00e9","livres","Madrid","Man","milieu","millions","paris","pour","Real","SaintGermain","sterling","terrain","TiretoHead39"],"articleSection":["Premier League"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/","url":"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/","name":"Man City, Paris Saint-Germain &#39;To Assy Tire-to-Head&#39; pour le milieu de terrain du Real Madrid de 59 millions de livres sterling cet \u00e9t\u00e9","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/#website"},"datePublished":"2025-03-12T01:48:25+00:00","dateModified":"2025-03-12T01:48:26+00:00","breadcrumb":{"@id":"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/footdavant.fr\/actualites\/man-city-paris-saint-germain-to-assy-tire-to-head-pour-le-milieu-de-terrain-du-real-madrid-de-59-millions-de-livres-sterling-cet-ete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/footdavant.fr\/actualites\/"},{"@type":"ListItem","position":2,"name":"Man City, Paris Saint-Germain &#39;To Assy Tire-to-Head&#39; pour le milieu de terrain du Real Madrid de 59 millions de livres sterling cet \u00e9t\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/footdavant.fr\/actualites\/#website","url":"https:\/\/footdavant.fr\/actualites\/","name":"Foot d'avant","description":"","publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/footdavant.fr\/actualites\/#organization","name":"Foot d'avant","url":"https:\/\/footdavant.fr\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","contentUrl":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","width":936,"height":549,"caption":"Foot d'avant"},"image":{"@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Footdavant\/","https:\/\/twitter.com\/FootdavantFr","https:\/\/www.instagram.com\/footdavant.fr\/"]},{"@type":"Person","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d","name":"Cl\u00e9ment","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","caption":"Cl\u00e9ment"},"sameAs":["https:\/\/footdavant.fr\/"]}]}},"_links":{"self":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/21207"}],"collection":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/comments?post=21207"}],"version-history":[{"count":1,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/21207\/revisions"}],"predecessor-version":[{"id":21209,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/21207\/revisions\/21209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media\/21208"}],"wp:attachment":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media?parent=21207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/categories?post=21207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/tags?post=21207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}