{"id":26473,"date":"2025-07-22T21:48:05","date_gmt":"2025-07-22T19:48:05","guid":{"rendered":"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/"},"modified":"2025-07-22T21:48:08","modified_gmt":"2025-07-22T19:48:08","slug":"lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere","status":"publish","type":"post","link":"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/","title":{"rendered":"LFC envisage de d\u00e9m\u00e9nager pour le d\u00e9fenseur qui n&#39;a quitt\u00e9 l&#39;Angleterre l&#39;ann\u00e9e derni\u00e8re"},"content":{"rendered":"<p><\/p>\n<div id=\"article-body\">\n<!-- Article Start --><\/p>\n<p>Liverpool envisage une d\u00e9cision pour le d\u00e9fenseur de Toulouse Charlie Cresswell cet \u00e9t\u00e9 alors qu&#39;Arne Slot cherche \u00e0 renforcer ses options d\u00e9fensives, c&#39;est selon GiveMesport (via Express).<\/p>\n<p>Jarrell Quansah a quitt\u00e9 le club pour rejoindre la tenue de Bundesliga, Bayer Leverkusen, plus t\u00f4t dans la fen\u00eatre, tandis qu&#39;Ibou Konate est entr\u00e9 dans les 12 derniers mois de son accord actuel Liverpoold et n&#39;a pas encore \u00e9t\u00e9 d&#39;accord sur un nouveau contrat.<\/p>\n<p>Le Real Madrid est cens\u00e9 garder un \u0153il sur la situation du Fran\u00e7ais alors qu&#39;ils tentent de l&#39;attirer dans la capitale espagnole lors d&#39;un transfert gratuit cette fois l&#39;ann\u00e9e prochaine.<\/p>\n<p>Virgil Van Dijk et Joe Gomez sont les seules autres options d\u00e9fensives centrales sup\u00e9rieures \u00e0 la disposition d&#39;Arne Slot.<\/p>\n<p>Cresswell a rejoint Toulouse de Leeds United l&#39;\u00e9t\u00e9 dernier dans une affaire de 3,8 millions de livres sterling (BBC Sport) et a impressionn\u00e9 en haut de parasites fran\u00e7ais ainsi que pour les U21 de l&#39;Angleterre, les jeunes Lions, les trois Lions ont r\u00e9ussi aux championnats d&#39;Europe le mois dernier.<\/p>\n<p>Le d\u00e9fenseur n\u00e9 \u00e0 Preston, qui a \u00e9galement pass\u00e9 du temps \u00e0 Millwall pr\u00e9c\u00e9demment, a fait 34 apparitions pour la partie de la Ligue 1 dernier et a marqu\u00e9 quatre buts et a enregistr\u00e9 deux passes d\u00e9cisives dans le processus (toutes les comp\u00e9titions toutes les comp\u00e9titions).<\/p>\n<p>\u00c0 6 pieds 2, il est une pr\u00e9sence imposante et quelqu&#39;un qui est d\u00e9j\u00e0 un joueur talentueux mais qui a \u00e9galement beaucoup de temps pour se d\u00e9velopper avec lui \u00e0 seulement 22 ans.<\/p>\n<p>Le rapport ajoute que l&#39;\u00e9quipe d&#39;Arne Slot n&#39;a pas fait de \u00abmouvement actif\u00bb pour l&#39;Anglais, qui a \u00e9t\u00e9 \u00e9tiquet\u00e9 comme \u00abexcellent\u00bb par l&#39;ancien patron de Millwall, Gary Rowett, (via Leeds partout), mais il est certainement sur le radar des champions de Premier League.<\/p>\n<p>Liverpool a \u00e9t\u00e9 tr\u00e8s actif sur le front jusqu&#39;\u00e0 pr\u00e9sent avec Jeremie Frimpong et Florian Wirtz sign\u00e9 de Bayer Leverkusen tandis que Milos Kerkez a rejoint le club depuis Bournemouth et l&#39;attaquant de Francfort Hugo Ekitike est pr\u00eat \u00e0 terminer son m\u00e9dical Reds \u00e0 tout moment.<\/p>\n<p>Le d\u00e9fenseur de Crystal Palace, Marc Guehi, est un autre nom qui a \u00e9t\u00e9 fortement li\u00e9 \u00e0 un d\u00e9m\u00e9nagement \u00e0 Anfield cet \u00e9t\u00e9 apr\u00e8s son entr\u00e9e r\u00e9cemment dans la derni\u00e8re ann\u00e9e de son accord au Selhurst Park.<\/p>\n<p><!-- Article End -->\t\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Liverpool envisage une d\u00e9cision pour le d\u00e9fenseur de Toulouse Charlie Cresswell cet \u00e9t\u00e9 alors qu&#39;Arne Slot cherche \u00e0 renforcer ses options d\u00e9fensives, c&#39;est selon GiveMesport<\/p>\n","protected":false},"author":1,"featured_media":26474,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[928,601,657,496,4294,4443,204,4238,51,243,3137],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LFC envisage de d\u00e9m\u00e9nager pour le d\u00e9fenseur qui n&#039;a quitt\u00e9 l&#039;Angleterre l&#039;ann\u00e9e derni\u00e8re<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LFC envisage de d\u00e9m\u00e9nager pour le d\u00e9fenseur qui n&#039;a quitt\u00e9 l&#039;Angleterre l&#039;ann\u00e9e derni\u00e8re\" \/>\n<meta property=\"og:description\" content=\"Liverpool envisage une d\u00e9cision pour le d\u00e9fenseur de Toulouse Charlie Cresswell cet \u00e9t\u00e9 alors qu&#039;Arne Slot cherche \u00e0 renforcer ses options d\u00e9fensives, c&#039;est selon GiveMesport\" \/>\n<meta property=\"og:url\" content=\"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/\" \/>\n<meta property=\"og:site_name\" content=\"Foot d&#039;avant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Footdavant\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-22T19:48:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-22T19:48:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2025\/07\/LFC-envisage-de-demenager-pour-le-defenseur-qui-n39a-quitte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:site\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/\"},\"author\":{\"name\":\"Cl\u00e9ment\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\"},\"headline\":\"LFC envisage de d\u00e9m\u00e9nager pour le d\u00e9fenseur qui n&#39;a quitt\u00e9 l&#39;Angleterre l&#39;ann\u00e9e derni\u00e8re\",\"datePublished\":\"2025-07-22T19:48:05+00:00\",\"dateModified\":\"2025-07-22T19:48:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/\"},\"wordCount\":430,\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"keywords\":[\"d\u00e9fenseur\",\"d\u00e9m\u00e9nager\",\"derni\u00e8re\",\"envisage\",\"l39Angleterre\",\"l39ann\u00e9e\",\"LFC\",\"n39a\",\"pour\",\"qui\",\"quitte\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/\",\"name\":\"LFC envisage de d\u00e9m\u00e9nager pour le d\u00e9fenseur qui n&#39;a quitt\u00e9 l&#39;Angleterre l&#39;ann\u00e9e derni\u00e8re\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\"},\"datePublished\":\"2025-07-22T19:48:05+00:00\",\"dateModified\":\"2025-07-22T19:48:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/footdavant.fr\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LFC envisage de d\u00e9m\u00e9nager pour le d\u00e9fenseur qui n&#39;a quitt\u00e9 l&#39;Angleterre l&#39;ann\u00e9e derni\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"name\":\"Foot d'avant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\",\"name\":\"Foot d'avant\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"contentUrl\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"width\":936,\"height\":549,\"caption\":\"Foot d'avant\"},\"image\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Footdavant\/\",\"https:\/\/twitter.com\/FootdavantFr\",\"https:\/\/www.instagram.com\/footdavant.fr\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\",\"name\":\"Cl\u00e9ment\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9ment\"},\"sameAs\":[\"https:\/\/footdavant.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LFC envisage de d\u00e9m\u00e9nager pour le d\u00e9fenseur qui n&#39;a quitt\u00e9 l&#39;Angleterre l&#39;ann\u00e9e derni\u00e8re","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/","og_locale":"fr_FR","og_type":"article","og_title":"LFC envisage de d\u00e9m\u00e9nager pour le d\u00e9fenseur qui n&#39;a quitt\u00e9 l&#39;Angleterre l&#39;ann\u00e9e derni\u00e8re","og_description":"Liverpool envisage une d\u00e9cision pour le d\u00e9fenseur de Toulouse Charlie Cresswell cet \u00e9t\u00e9 alors qu&#39;Arne Slot cherche \u00e0 renforcer ses options d\u00e9fensives, c&#39;est selon GiveMesport","og_url":"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/","og_site_name":"Foot d&#039;avant","article_publisher":"https:\/\/www.facebook.com\/Footdavant\/","article_published_time":"2025-07-22T19:48:05+00:00","article_modified_time":"2025-07-22T19:48:08+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2025\/07\/LFC-envisage-de-demenager-pour-le-defenseur-qui-n39a-quitte.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9ment","twitter_card":"summary_large_image","twitter_creator":"@FootdavantFr","twitter_site":"@FootdavantFr","twitter_misc":{"\u00c9crit par":"Cl\u00e9ment","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/#article","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/"},"author":{"name":"Cl\u00e9ment","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d"},"headline":"LFC envisage de d\u00e9m\u00e9nager pour le d\u00e9fenseur qui n&#39;a quitt\u00e9 l&#39;Angleterre l&#39;ann\u00e9e derni\u00e8re","datePublished":"2025-07-22T19:48:05+00:00","dateModified":"2025-07-22T19:48:08+00:00","mainEntityOfPage":{"@id":"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/"},"wordCount":430,"publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"keywords":["d\u00e9fenseur","d\u00e9m\u00e9nager","derni\u00e8re","envisage","l39Angleterre","l39ann\u00e9e","LFC","n39a","pour","qui","quitte"],"articleSection":["Football"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/","url":"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/","name":"LFC envisage de d\u00e9m\u00e9nager pour le d\u00e9fenseur qui n&#39;a quitt\u00e9 l&#39;Angleterre l&#39;ann\u00e9e derni\u00e8re","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/#website"},"datePublished":"2025-07-22T19:48:05+00:00","dateModified":"2025-07-22T19:48:08+00:00","breadcrumb":{"@id":"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/footdavant.fr\/actualites\/lfc-envisage-de-demenager-pour-le-defenseur-qui-na-quitte-langleterre-lannee-derniere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/footdavant.fr\/actualites\/"},{"@type":"ListItem","position":2,"name":"LFC envisage de d\u00e9m\u00e9nager pour le d\u00e9fenseur qui n&#39;a quitt\u00e9 l&#39;Angleterre l&#39;ann\u00e9e derni\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/footdavant.fr\/actualites\/#website","url":"https:\/\/footdavant.fr\/actualites\/","name":"Foot d'avant","description":"","publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/footdavant.fr\/actualites\/#organization","name":"Foot d'avant","url":"https:\/\/footdavant.fr\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","contentUrl":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","width":936,"height":549,"caption":"Foot d'avant"},"image":{"@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Footdavant\/","https:\/\/twitter.com\/FootdavantFr","https:\/\/www.instagram.com\/footdavant.fr\/"]},{"@type":"Person","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d","name":"Cl\u00e9ment","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","caption":"Cl\u00e9ment"},"sameAs":["https:\/\/footdavant.fr\/"]}]}},"_links":{"self":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/26473"}],"collection":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/comments?post=26473"}],"version-history":[{"count":1,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/26473\/revisions"}],"predecessor-version":[{"id":26475,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/26473\/revisions\/26475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media\/26474"}],"wp:attachment":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media?parent=26473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/categories?post=26473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/tags?post=26473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}