{"id":37422,"date":"2026-05-13T14:48:17","date_gmt":"2026-05-13T12:48:17","guid":{"rendered":"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/"},"modified":"2026-05-13T14:48:18","modified_gmt":"2026-05-13T12:48:18","slug":"nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3","status":"publish","type":"post","link":"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/","title":{"rendered":"Nouvelles du transfert de Chelsea: un paria de 38,9 millions de livres sterling offert une bou\u00e9e de sauvetage en Premier League alors que les rivaux sont \u00ab confiants \u00bb dans l&#39;accord d&#39;\u00e9t\u00e9"},"content":{"rendered":"<div itemprop=\"articleBody\">\n<p>Le d\u00e9fenseur de Chelsea, Axel Disasi, serait devenu une cible de transfert pour Leeds United lors du mercato estival.<\/p>\n<p>Le joueur de 28 ans a \u00e9t\u00e9 en grande partie exclu de l\u2019\u00e9quipe des Blues sous Enzo Maresca et n\u2019a pas jou\u00e9 une seule minute de la saison 2025-26 avant son pr\u00eat en janvier \u00e0 West Ham United.<\/p>\n<p>Disasi est rapidement devenu un joueur cl\u00e9 pour les Irons, disputant les 90 minutes compl\u00e8tes de chacun de leurs 11 derniers matches de Premier League alors que l&#39;\u00e9quipe de Nuno Espirito Santo se bat pour \u00e9viter la rel\u00e9gation.<\/p>\n<p>Cependant, le sort de survie de West Ham est d\u00e9sormais hors de leur contr\u00f4le avant le choc de dimanche avec le leader Arsenal, alors que les Hammers occupent la 18e place du classement de la Premier League, un point derri\u00e8re Tottenham Hotspur.<\/p>\n<p>West Ham n&#39;a ni l&#39;option ni l&#39;obligation de rendre le s\u00e9jour de Disasi permanent, et une r\u00e9trogradation en Championnat exclurait toute chance que le club de la capitale garde le Fran\u00e7ais inscrit au stade de Londres.<\/p>\n<h2>Leeds \u00ab confiant \u00bb dans l&#39;accord d&#39;\u00e9t\u00e9 pour Axel Disasi de Chelsea<\/h2>\n<div>\n<div>\n<div>\n<p>\u00a9 Imago \/ APL<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>Disasi est donc destin\u00e9 \u00e0 revenir \u00e0 Chelsea cet \u00e9t\u00e9, et il est possible qu&#39;il relance sa carri\u00e8re de Blues sous la direction du nouveau manager pendant la pr\u00e9-saison.<\/p>\n<p>Un transfert ailleurs reste cependant consid\u00e9r\u00e9 comme la prochaine \u00e9tape la plus probable pour Disasi, et selon <em>Initi\u00e9 au football<\/em>l&#39;ancien Mon\u00e9gasque pourrait \u00eatre \u00ab d\u00e9bauch\u00e9 \u00bb par Leeds.<\/p>\n<p>Les Merengues \u00e9taient cens\u00e9s vouloir amener Disasi \u00e0 Elland Road en janvier, pour ensuite \u00eatre devanc\u00e9s au poste par West Ham, mais ils n&#39;ont pas perdu de vue le d\u00e9fenseur central.<\/p>\n<p>Le rapport ajoute que Leeds est \u00ab\u00a0confiant\u00a0\u00bb dans la conclusion d&#39;un accord pour signer Disasi, qui remplacerait Sebastiaan Bornauw, en disgr\u00e2ce, pour la deuxi\u00e8me saison cons\u00e9cutive des Blancos dans l&#39;\u00e9lite.<\/p>\n<p>Les hommes de Farke n&#39;ont pas encore assur\u00e9 leur survie math\u00e9matique, mais aucune \u00e9quipe n&#39;a jamais \u00e9t\u00e9 rel\u00e9gu\u00e9e de la Premier League avec son total actuel de 43 points. et ils seront en s\u00e9curit\u00e9 s&#39;ils \u00e9galent ou am\u00e9liorent le r\u00e9sultat de West Ham lors de la semaine 36.<\/p>\n<p>Chelsea a pay\u00e9 38,9 millions de livres sterling pour recruter Disasi de Monaco en 2023, depuis lors, le Fran\u00e7ais a marqu\u00e9 cinq buts et fourni deux passes d\u00e9cisives en 61 apparitions pour les g\u00e9ants de l&#39;ouest de Londres.<\/p>\n<h2>Quels autres joueurs Chelsea pourrait-il vendre cet \u00e9t\u00e9 ?<\/h2>\n<div>\n<div>\n<div><img decoding=\"async\" data-img-id=\"159565\" class=\"lazy\" loading=\"lazy\" src=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2026\/05\/1778676497_712_Nouvelles-du-transfert-de-Chelsea-un-paria-de-389-millions.webp\"\/><\/p>\n<p>\u00a9 Iconsport \/ Marco Steinbrenner\/DeFodi Images<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>Disasi n&#39;est pas le seul d\u00e9fenseur central fran\u00e7ais qui pourrait quitter Stamford Bridge, car son ancien co\u00e9quipier de Monaco Benoit Badiashile n&#39;est qu&#39;un joueur mineur et pourrait chercher plus de minutes ailleurs.<\/p>\n<p>Les Bleus n&#39;ont pas autant de bois mort \u00e0 \u00e9liminer que l&#39;\u00e9t\u00e9 dernier, mais les autres joueurs pr\u00eat\u00e9s Nicolas Jackson, Tyrique George, David Datro Fofana et Marc Guiu devraient \u00e9galement \u00eatre \u00e0 la recherche de nouvelles destinations.<\/p>\n<p>Les d\u00e9parts de Jackson, Datro Fofana et Guiu ouvriraient la voie \u00e0 la signature d&#39;un nouvel attaquant, et Chelsea envisagerait apparemment une d\u00e9cision choc pour un ancien attaquant de Premier League brutalement limog\u00e9 par son club actuel.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9fenseur de Chelsea, Axel Disasi, serait devenu une cible de transfert pour Leeds United lors du mercato estival. Le joueur de 28 ans a<\/p>\n","protected":false},"author":1,"featured_media":34119,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[318,1275,171,11953,4968,19,4350,202,93,115,114,461,2600,5237,201,4103,1276,45,116,700,92],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nouvelles du transfert de Chelsea: un paria de 38,9 millions de livres sterling offert une bou\u00e9e de sauvetage en Premier League alors que les rivaux sont \u00ab confiants \u00bb dans l&#039;accord d&#039;\u00e9t\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelles du transfert de Chelsea: un paria de 38,9 millions de livres sterling offert une bou\u00e9e de sauvetage en Premier League alors que les rivaux sont \u00ab confiants \u00bb dans l&#039;accord d&#039;\u00e9t\u00e9\" \/>\n<meta property=\"og:description\" content=\"Le d\u00e9fenseur de Chelsea, Axel Disasi, serait devenu une cible de transfert pour Leeds United lors du mercato estival. Le joueur de 28 ans a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/\" \/>\n<meta property=\"og:site_name\" content=\"Foot d&#039;avant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Footdavant\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T12:48:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T12:48:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2026\/02\/1770137285_Nouvelles-du-transfert-de-Chelsea-Hijack-pour.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:site\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/\"},\"author\":{\"name\":\"Cl\u00e9ment\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\"},\"headline\":\"Nouvelles du transfert de Chelsea: un paria de 38,9 millions de livres sterling offert une bou\u00e9e de sauvetage en Premier League alors que les rivaux sont \u00ab confiants \u00bb dans l&#39;accord d&#39;\u00e9t\u00e9\",\"datePublished\":\"2026-05-13T12:48:17+00:00\",\"dateModified\":\"2026-05-13T12:48:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/\"},\"wordCount\":583,\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"keywords\":[\"alors\",\"bou\u00e9e\",\"Chelsea\",\"confiants\",\"d39\u00e9t\u00e9\",\"dans\",\"l39accord\",\"League\",\"les\",\"livres\",\"millions\",\"Nouvelles\",\"offert\",\"paria\",\"Premier\",\"rivaux\",\"sauvetage\",\"sont\",\"sterling\",\"transfert\",\"une\"],\"articleSection\":[\"Premier League\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/\",\"name\":\"Nouvelles du transfert de Chelsea: un paria de 38,9 millions de livres sterling offert une bou\u00e9e de sauvetage en Premier League alors que les rivaux sont \u00ab confiants \u00bb dans l&#39;accord d&#39;\u00e9t\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\"},\"datePublished\":\"2026-05-13T12:48:17+00:00\",\"dateModified\":\"2026-05-13T12:48:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/footdavant.fr\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles du transfert de Chelsea: un paria de 38,9 millions de livres sterling offert une bou\u00e9e de sauvetage en Premier League alors que les rivaux sont \u00ab confiants \u00bb dans l&#39;accord d&#39;\u00e9t\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"name\":\"Foot d'avant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\",\"name\":\"Foot d'avant\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"contentUrl\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"width\":936,\"height\":549,\"caption\":\"Foot d'avant\"},\"image\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Footdavant\/\",\"https:\/\/twitter.com\/FootdavantFr\",\"https:\/\/www.instagram.com\/footdavant.fr\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\",\"name\":\"Cl\u00e9ment\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9ment\"},\"sameAs\":[\"https:\/\/footdavant.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelles du transfert de Chelsea: un paria de 38,9 millions de livres sterling offert une bou\u00e9e de sauvetage en Premier League alors que les rivaux sont \u00ab confiants \u00bb dans l&#39;accord d&#39;\u00e9t\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvelles du transfert de Chelsea: un paria de 38,9 millions de livres sterling offert une bou\u00e9e de sauvetage en Premier League alors que les rivaux sont \u00ab confiants \u00bb dans l&#39;accord d&#39;\u00e9t\u00e9","og_description":"Le d\u00e9fenseur de Chelsea, Axel Disasi, serait devenu une cible de transfert pour Leeds United lors du mercato estival. Le joueur de 28 ans a","og_url":"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/","og_site_name":"Foot d&#039;avant","article_publisher":"https:\/\/www.facebook.com\/Footdavant\/","article_published_time":"2026-05-13T12:48:17+00:00","article_modified_time":"2026-05-13T12:48:18+00:00","og_image":[{"width":720,"height":410,"url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2026\/02\/1770137285_Nouvelles-du-transfert-de-Chelsea-Hijack-pour.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9ment","twitter_card":"summary_large_image","twitter_creator":"@FootdavantFr","twitter_site":"@FootdavantFr","twitter_misc":{"\u00c9crit par":"Cl\u00e9ment","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/#article","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/"},"author":{"name":"Cl\u00e9ment","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d"},"headline":"Nouvelles du transfert de Chelsea: un paria de 38,9 millions de livres sterling offert une bou\u00e9e de sauvetage en Premier League alors que les rivaux sont \u00ab confiants \u00bb dans l&#39;accord d&#39;\u00e9t\u00e9","datePublished":"2026-05-13T12:48:17+00:00","dateModified":"2026-05-13T12:48:18+00:00","mainEntityOfPage":{"@id":"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/"},"wordCount":583,"publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"keywords":["alors","bou\u00e9e","Chelsea","confiants","d39\u00e9t\u00e9","dans","l39accord","League","les","livres","millions","Nouvelles","offert","paria","Premier","rivaux","sauvetage","sont","sterling","transfert","une"],"articleSection":["Premier League"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/","url":"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/","name":"Nouvelles du transfert de Chelsea: un paria de 38,9 millions de livres sterling offert une bou\u00e9e de sauvetage en Premier League alors que les rivaux sont \u00ab confiants \u00bb dans l&#39;accord d&#39;\u00e9t\u00e9","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/#website"},"datePublished":"2026-05-13T12:48:17+00:00","dateModified":"2026-05-13T12:48:18+00:00","breadcrumb":{"@id":"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/footdavant.fr\/actualites\/nouvelles-du-transfert-de-chelsea-un-paria-de-389-millions-de-livres-sterling-offert-une-bouee-de-sauvetage-en-premier-league-alors-que-les-rivaux-sont-confiants-dans-laccord-d3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/footdavant.fr\/actualites\/"},{"@type":"ListItem","position":2,"name":"Nouvelles du transfert de Chelsea: un paria de 38,9 millions de livres sterling offert une bou\u00e9e de sauvetage en Premier League alors que les rivaux sont \u00ab confiants \u00bb dans l&#39;accord d&#39;\u00e9t\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/footdavant.fr\/actualites\/#website","url":"https:\/\/footdavant.fr\/actualites\/","name":"Foot d'avant","description":"","publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/footdavant.fr\/actualites\/#organization","name":"Foot d'avant","url":"https:\/\/footdavant.fr\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","contentUrl":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","width":936,"height":549,"caption":"Foot d'avant"},"image":{"@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Footdavant\/","https:\/\/twitter.com\/FootdavantFr","https:\/\/www.instagram.com\/footdavant.fr\/"]},{"@type":"Person","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d","name":"Cl\u00e9ment","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","caption":"Cl\u00e9ment"},"sameAs":["https:\/\/footdavant.fr\/"]}]}},"_links":{"self":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/37422"}],"collection":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/comments?post=37422"}],"version-history":[{"count":1,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/37422\/revisions"}],"predecessor-version":[{"id":37423,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/37422\/revisions\/37423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media\/34119"}],"wp:attachment":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media?parent=37422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/categories?post=37422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/tags?post=37422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}