{"id":8413,"date":"2024-05-06T17:49:08","date_gmt":"2024-05-06T15:49:08","guid":{"rendered":"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/"},"modified":"2024-05-06T17:49:08","modified_gmt":"2024-05-06T15:49:08","slug":"le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid","status":"publish","type":"post","link":"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/","title":{"rendered":"Le Bayern Munich subit une double blessure avant le choc contre le Real Madrid"},"content":{"rendered":"<p>Le Bayern Munich pourrait manquer Eric Dier pour la demi-finale retour de la Ligue des champions mercredi contre le Real Madrid, tandis que Raphael Guerreiro est d\u00e9finitivement absent.<\/p>\n<div id=\"article_body\" itemprop=\"articleBody\">\n<h3 class=\"firstPara\">\n<strong class=\"autotag\">Bayern Munich<\/strong> transpirent \u00e0 cause de la forme physique de <strong class=\"autotag\">\u00c9ric Dier<\/strong> pour le mercredi <strong class=\"autotag\">Ligue des champions<\/strong> demi-finale retour contre <strong class=\"autotag\">Real Madrid<\/strong>alors que <strong class=\"autotag\">Rapha\u00ebl Guerreiro<\/strong> a \u00e9t\u00e9 exclu en raison d&#39;un probl\u00e8me \u00e0 la cheville.<\/h3>\n<p>Guerreiro a \u00e9t\u00e9 expuls\u00e9 \u00e0 la 17e minute du choc de Bundesliga samedi contre Stuttgart, et les g\u00e9ants de Munich ont maintenant confirm\u00e9 qu&#39;il risquait d&#39;\u00eatre absent en raison d&#39;une blessure \u00e0 la cheville.<\/p>\n<p>Le Bayern a fix\u00e9 un d\u00e9lai pour son absence, mais il manquera certainement \u00e0 l&#39;appel. <strong class=\"autotag\">Thomas Tuchel<\/strong>L&#39;\u00e9quipe de Madrid se rend au Real Madrid pour le match retour de la demi-finale de Coupe d&#39;Europe.<\/p>\n<p>\u00ab\u00a0Le FC Bayern devra se passer de Raphael Guerreiro lors des prochains matches. Le Portugais s&#39;est bless\u00e9 aux ligaments et \u00e0 la capsule de la cheville lors du match de Bundesliga samedi \u00e0 Stuttgart, comme l&#39;a confirm\u00e9 un scanner du service m\u00e9dical du FC Bayern\u00a0\u00bb, peut-on lire. un communiqu\u00e9 du club allemand.<\/p>\n<p>Dier, quant \u00e0 lui, s&#39;est bless\u00e9 \u00e0 la t\u00eate au cours du m\u00eame match lorsqu&#39;il a r\u00e9alis\u00e9 une t\u00eate qui a sauv\u00e9 le but.<\/p>\n<p class=\"imgI\">\n<h2>Raphael Guerreiro absent, Eric Dier incertain pour le match contre le Real Madrid<\/h2>\n<p>L&#39;Anglais, pr\u00eat\u00e9 au Bayern par Tottenham Hotspur, s&#39;est retrouv\u00e9 avec une coupure \u00e0 la t\u00eate plus t\u00f4t dans la comp\u00e9tition, et celle-ci a ensuite rouvert lorsqu&#39;il a repouss\u00e9 un effort de <strong class=\"autotag\">Serhou Guirassy<\/strong> dans l&#39;affaire de la Bundesliga.<\/p>\n<p>Dier \u00e9tait band\u00e9 et a jou\u00e9 jusqu&#39;\u00e0 la pause, avant d&#39;\u00eatre remplac\u00e9.<\/p>\n<p>Apr\u00e8s le match, l&#39;entra\u00eeneur du Bayern, Tuchel, a fait le point sur la situation, le d\u00e9fenseur central \u00e9tant d\u00e9sormais consid\u00e9r\u00e9 comme un doute pour le match dans la capitale espagnole.<\/p>\n<p>\u00ab\u00a0Eric a d\u00fb recoudre la blessure \u00e0 la t\u00eate qui s&#39;est ensuite rouverte, donc \u00e0 un moment donn\u00e9, nous avons dit que c&#39;\u00e9tait suffisant. Nous ne voulions pas prendre de risque\u00a0\u00bb, a d\u00e9clar\u00e9 Tuchel aux journalistes.<\/p>\n<p>L&#39;Allemand a \u00e9galement r\u00e9v\u00e9l\u00e9 que Dier souffrait d&#39;un probl\u00e8me \u00e0 la cuisse, mais a insist\u00e9 sur le fait que la raison de son forfait samedi \u00e9tait une blessure \u00e0 la t\u00eate.<\/p>\n<p class=\"imgI\"><img decoding=\"async\" loading=\"lazy\" class=\"l\" src=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/05\/Le-Bayern-Munich-subit-une-double-blessure-avant-le-choc.jpg\" title=\"L&#39;entra\u00eeneur du Bayern Munich Thomas Tuchel r\u00e9agit le 26 juillet 2023\" alt=\"L&#39;entra\u00eeneur du Bayern Munich Thomas Tuchel r\u00e9agit le 26 juillet 2023\" width=\"640\" height=\"480\"><\/p>\n<h2>Le Bayern a des probl\u00e8mes d\u00e9fensifs avant son d\u00e9placement \u00e0 Madrid<\/h2>\n<p>\u00ab\u00a0Dier a senti un petit quelque chose dans sa cuisse avant le match, mais ce n&#39;\u00e9tait pas la raison (il a \u00e9t\u00e9 remplac\u00e9) &#8211; c&#39;\u00e9tait \u00e0 cause du coup \u00e0 la t\u00eate. Nous ne pouvions plus prendre de risques avec lui\u00a0\u00bb, a-t-il ajout\u00e9.<\/p>\n<p>\u00ab\u00a0Nous avons alors pris un risque avec Upa (<strong class=\"autotag\">Dayot Upamecano<\/strong>) qui n&#39;\u00e9tait pas cens\u00e9 jouer plus de 30 minutes.  C&#39;est malheureusement l&#39;histoire de notre saison.\u00a0\u00bb<\/p>\n<p><strong class=\"autotag\">Matthijs de Ligt<\/strong> a \u00e9galement rat\u00e9 les deux derniers matches du Bayern en raison d&#39;un probl\u00e8me au genou, et il reste \u00e0 voir s&#39;il sera impliqu\u00e9 contre le Real Madrid.<\/p>\n<p>Si Dier et De Ligt ne parviennent pas \u00e0 y parvenir, Upamecano jouera probablement aux c\u00f4t\u00e9s <strong class=\"autotag\">Kim Min Jae<\/strong> au milieu de la d\u00e9fense contre le Real Madrid.<\/p>\n<p><strong class=\"autotag\">Leroy San\u00e9<\/strong> et <strong class=\"autotag\">Harry Kane<\/strong> \u00e9taient sur la feuille de match du Bayern lors du match aller de leur demi-finale contre les champions de la Liga, tandis que <strong class=\"autotag\">Vinicius Junior<\/strong> a marqu\u00e9 un doubl\u00e9 pour l&#39;\u00e9quipe espagnole.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le Bayern Munich pourrait manquer Eric Dier pour la demi-finale retour de la Ligue des champions mercredi contre le Real Madrid, tandis que Raphael Guerreiro<\/p>\n","protected":false},"author":1,"featured_media":8414,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[491,340,15,332,20,317,303,341,302,366,92],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Bayern Munich subit une double blessure avant le choc contre le Real Madrid<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Bayern Munich subit une double blessure avant le choc contre le Real Madrid\" \/>\n<meta property=\"og:description\" content=\"Le Bayern Munich pourrait manquer Eric Dier pour la demi-finale retour de la Ligue des champions mercredi contre le Real Madrid, tandis que Raphael Guerreiro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Foot d&#039;avant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Footdavant\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-06T15:49:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/05\/Le-Bayern-Munich-subit-une-double-blessure-avant-le-choc.JPG\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:site\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/\"},\"author\":{\"name\":\"Cl\u00e9ment\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\"},\"headline\":\"Le Bayern Munich subit une double blessure avant le choc contre le Real Madrid\",\"datePublished\":\"2024-05-06T15:49:08+00:00\",\"dateModified\":\"2024-05-06T15:49:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/\"},\"wordCount\":598,\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"keywords\":[\"avant\",\"Bayern\",\"Blessure\",\"choc\",\"contre\",\"doubl\u00e9\",\"Madrid\",\"Munich\",\"Real\",\"subit\",\"une\"],\"articleSection\":[\"Champions League\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/\",\"name\":\"Le Bayern Munich subit une double blessure avant le choc contre le Real Madrid\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\"},\"datePublished\":\"2024-05-06T15:49:08+00:00\",\"dateModified\":\"2024-05-06T15:49:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/footdavant.fr\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Bayern Munich subit une double blessure avant le choc contre le Real Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"name\":\"Foot d'avant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\",\"name\":\"Foot d'avant\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"contentUrl\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"width\":936,\"height\":549,\"caption\":\"Foot d'avant\"},\"image\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Footdavant\/\",\"https:\/\/twitter.com\/FootdavantFr\",\"https:\/\/www.instagram.com\/footdavant.fr\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\",\"name\":\"Cl\u00e9ment\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9ment\"},\"sameAs\":[\"https:\/\/footdavant.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Bayern Munich subit une double blessure avant le choc contre le Real Madrid","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Bayern Munich subit une double blessure avant le choc contre le Real Madrid","og_description":"Le Bayern Munich pourrait manquer Eric Dier pour la demi-finale retour de la Ligue des champions mercredi contre le Real Madrid, tandis que Raphael Guerreiro","og_url":"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/","og_site_name":"Foot d&#039;avant","article_publisher":"https:\/\/www.facebook.com\/Footdavant\/","article_published_time":"2024-05-06T15:49:08+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/05\/Le-Bayern-Munich-subit-une-double-blessure-avant-le-choc.JPG","type":"image\/jpeg"}],"author":"Cl\u00e9ment","twitter_card":"summary_large_image","twitter_creator":"@FootdavantFr","twitter_site":"@FootdavantFr","twitter_misc":{"\u00c9crit par":"Cl\u00e9ment","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/#article","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/"},"author":{"name":"Cl\u00e9ment","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d"},"headline":"Le Bayern Munich subit une double blessure avant le choc contre le Real Madrid","datePublished":"2024-05-06T15:49:08+00:00","dateModified":"2024-05-06T15:49:08+00:00","mainEntityOfPage":{"@id":"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/"},"wordCount":598,"publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"keywords":["avant","Bayern","Blessure","choc","contre","doubl\u00e9","Madrid","Munich","Real","subit","une"],"articleSection":["Champions League"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/","url":"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/","name":"Le Bayern Munich subit une double blessure avant le choc contre le Real Madrid","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/#website"},"datePublished":"2024-05-06T15:49:08+00:00","dateModified":"2024-05-06T15:49:08+00:00","breadcrumb":{"@id":"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/footdavant.fr\/actualites\/le-bayern-munich-subit-une-double-blessure-avant-le-choc-contre-le-real-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/footdavant.fr\/actualites\/"},{"@type":"ListItem","position":2,"name":"Le Bayern Munich subit une double blessure avant le choc contre le Real Madrid"}]},{"@type":"WebSite","@id":"https:\/\/footdavant.fr\/actualites\/#website","url":"https:\/\/footdavant.fr\/actualites\/","name":"Foot d'avant","description":"","publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/footdavant.fr\/actualites\/#organization","name":"Foot d'avant","url":"https:\/\/footdavant.fr\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","contentUrl":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","width":936,"height":549,"caption":"Foot d'avant"},"image":{"@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Footdavant\/","https:\/\/twitter.com\/FootdavantFr","https:\/\/www.instagram.com\/footdavant.fr\/"]},{"@type":"Person","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d","name":"Cl\u00e9ment","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","caption":"Cl\u00e9ment"},"sameAs":["https:\/\/footdavant.fr\/"]}]}},"_links":{"self":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/8413"}],"collection":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/comments?post=8413"}],"version-history":[{"count":1,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/8413\/revisions"}],"predecessor-version":[{"id":8415,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/8413\/revisions\/8415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media\/8414"}],"wp:attachment":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media?parent=8413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/categories?post=8413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/tags?post=8413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}