{"id":8816,"date":"2024-05-16T10:48:55","date_gmt":"2024-05-16T08:48:55","guid":{"rendered":"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/"},"modified":"2024-05-16T10:48:56","modified_gmt":"2024-05-16T08:48:56","slug":"cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool","status":"publish","type":"post","link":"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/","title":{"rendered":"\u00ab\u00a0Cela arrivera\u00a0\u00bb \u2013 Arne Slot r\u00e9v\u00e8le le calendrier pr\u00e9vu de l&#39;annonce de Liverpool"},"content":{"rendered":"<p>Le manager de Feyenoord, Arne Slot, r\u00e9v\u00e8le que ce n&#39;est qu&#39;une \u00ab\u00a0question de jours\u00a0\u00bb avant qu&#39;il ne soit confirm\u00e9 comme successeur de Jurgen Klopp \u00e0 Liverpool.<\/p>\n<div id=\"article_body\" itemprop=\"articleBody\">\n<h3 class=\"firstPara\">\n<strong class=\"autotag\">Feyenoord<\/strong> manager et entrant <strong class=\"autotag\">Liverpool<\/strong> l&#39;entra\u00eeneur-chef <strong class=\"autotag\">Machine \u00e0 sous Arne<\/strong> a fourni une mise \u00e0 jour sur le moment o\u00f9 les fans des Reds peuvent s&#39;attendre \u00e0 une annonce officielle de son arriv\u00e9e \u00e0 Anfield.<\/h3>\n<p>Le N\u00e9erlandais est sur le point d&#39;\u00eatre embauch\u00e9 par les g\u00e9ants du Merseyside pour succ\u00e9der \u00e0 <strong class=\"autotag\">J\u00fcrgen Klopp<\/strong>qui ne prendra en charge que deux matchs suppl\u00e9mentaires pour Liverpool avant de quitter son poste.<\/p>\n<p>Liverpool a conclu un accord pour Slot apr\u00e8s le patron du Bayer Leverkusen <strong class=\"autotag\">Xabi Alonso<\/strong> a choisi de rester fid\u00e8le aux champions allemands, tout en \u00e9tant li\u00e9 aux dirigeants du Sporting Lisbonne <strong class=\"autotag\">Ruben Amorim<\/strong> n\u2019a rien donn\u00e9 non plus.<\/p>\n<p>Slot n&#39;a conclu un nouvel accord avec Feyenoord que l&#39;\u00e9t\u00e9 dernier pour durer jusqu&#39;en 2026, mais Liverpool aurait d\u00e9sormais conclu un accord sur une indemnisation d&#39;environ 9,4 millions de livres sterling \u2013 dont un montant initial de 7,7 millions de livres sterling \u2013 avec ses homologues n\u00e9erlandais.<\/p>\n<p>Slot a d\u00e9j\u00e0 affirm\u00e9 \u00e0 plusieurs reprises qu&#39;il aspirait au poste \u00e0 Anfield et esp\u00e8re que son passage au Merseyside se d\u00e9roulera sans accroc, mais ni Liverpool ni Feyenoord n&#39;ont encore fourni de confirmation officielle.<\/p>\n<p class=\"imgI\">\n<h2>Emplacement\u00a0:\u00a0\u00ab\u00a0L&#39;annonce est dans quelques jours\u00a0\u00bb<\/h2>\n<p>On pense que les Reds se battent pour amener l&#39;\u00e9quipe de 45 ans \u00e0 Anfield pour le remplacer. <strong class=\"autotag\">Pep Lijnders<\/strong>, <strong class=\"autotag\">Peter Krawietz<\/strong> et <strong class=\"autotag\">Vitor Matos<\/strong>qui seront tous \u00e9galement sur le d\u00e9part cet \u00e9t\u00e9.<\/p>\n<p>Alors que Liverpool fait tout son possible pour embaucher <strong class=\"autotag\">Sibke Hulshoff<\/strong>, <strong class=\"autotag\">\u00c9tienne Reijnen<\/strong> et <strong class=\"autotag\">Ruben Peeters<\/strong>qui pourrait apparemment co\u00fbter 2 millions de livres sterling suppl\u00e9mentaires, Slot a d\u00e9clar\u00e9 aux m\u00e9dias ce week-end que la confirmation n&#39;\u00e9tait qu&#39;une question de jours.<\/p>\n<p>\u00ab\u00a0Je ne peux pas r\u00e9v\u00e9ler les d\u00e9tails pour le moment, mais il ne s&#39;agit pas de mon contrat. Il y a une combinaison de facteurs qui expliquent pourquoi il n&#39;y a pas encore d&#39;annonce\u00a0\u00bb, <em>Le miroir<\/em> cite Slot comme disant.<\/p>\n<p>\u00ab\u00a0Mais ne vous inqui\u00e9tez pas. Cela arrivera. Je sais que je l&#39;ai dit \u00e0 chaque fois au cours de la semaine derni\u00e8re, mais je pense que ce n&#39;est vraiment qu&#39;une question de jours maintenant. Certaines choses ont juste besoin de plus de temps.\u00a0\u00bb<\/p>\n<p>Slot a d\u00e9but\u00e9 sa carri\u00e8re de manager avec l&#39;AZ Alkmaar et Cambuur avant de prendre les r\u00eanes de Feyenoord en 2021, remportant le titre d&#39;Eredivisie lors de sa deuxi\u00e8me saison \u00e0 la t\u00eate et snobe l&#39;ann\u00e9e derni\u00e8re l&#39;int\u00e9r\u00eat de Tottenham Hotspur pour rester \u00e0 Rotterdam.<\/p>\n<h2>Quels joueurs de Feyenoord Slot pourrait-il signer pour Liverpool ?<\/h2>\n<p class=\"imgI\"><img decoding=\"async\" loading=\"lazy\" class=\"l\" src=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/05\/Cela-arrivera-\u2013-Arne-Slot-revele-le-calendrier-prevu-de.JPG\" title=\"Mats Wieffer en action pour les Pays-Bas en novembre 2023\" alt=\"Mats Wieffer en action pour les Pays-Bas en novembre 2023\" width=\"640\" height=\"480\"><\/p>\n<p>En plus de braconner Slot et potentiellement toute son \u00e9quipe d&#39;entra\u00eeneurs de Feyenoord, Liverpool pourrait \u00e9galement essayer d&#39;amener certains des joueurs de confiance du N\u00e9erlandais \u00e0 Anfield pour l&#39;\u00e8re post-Klopp.<\/p>\n<p>Un nouveau d\u00e9fenseur central est consid\u00e9r\u00e9 comme la priorit\u00e9 absolue de Liverpool cet \u00e9t\u00e9, et l&#39;agent du d\u00e9fenseur buteur de Feyenoord <strong class=\"autotag\">David Hancko<\/strong> a d\u00e9clar\u00e9 qu&#39;il y avait un int\u00e9r\u00eat des Reds et du Paris Saint-Germain pour son client.<\/p>\n<p><strong class=\"autotag\">Lutsharel Geertruida<\/strong> pourrait fournir une option alternative au c\u0153ur de la d\u00e9fense et a \u00e9t\u00e9 vu lors du r\u00e9cent match nul de Liverpool contre West Ham United, bien qu&#39;il ait largement jou\u00e9 le r\u00f4le d&#39;arri\u00e8re lat\u00e9ral pour les g\u00e9ants n\u00e9erlandais cette saison.<\/p>\n<p>Les Reds devraient-ils \u00e9galement renforcer leur milieu de terrain, li\u00e9 \u00e0 Barcelone <strong class=\"autotag\">Mats Wieffer<\/strong> ou <strong class=\"autotag\">Bois Quinten<\/strong> &#8211; fr\u00e8re jumeau d&#39;Arsenal <strong class=\"autotag\">Jurrien Bois<\/strong> &#8211; pourrait \u00eatre des options int\u00e9ressantes et un attaquant <strong class=\"autotag\">Santiago Gim\u00e9nez<\/strong> devrait \u00eatre au centre d\u2019une vente aux ench\u00e8res \u00e0 plusieurs \u00e9quipes cet \u00e9t\u00e9.<\/p>\n<p>Il est peu probable que la confirmation de l&#39;arriv\u00e9e de Slot arrive avant que Liverpool n&#39;affronte Aston Villa lundi, dans ce qui sera le dernier match de Klopp sur la route avant la visite des Wolverhampton Wanderers \u00e0 Anfield pour son match d&#39;adieu huit jours plus tard.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le manager de Feyenoord, Arne Slot, r\u00e9v\u00e8le que ce n&#39;est qu&#39;une \u00ab\u00a0question de jours\u00a0\u00bb avant qu&#39;il ne soit confirm\u00e9 comme successeur de Jurgen Klopp \u00e0<\/p>\n","protected":false},"author":1,"featured_media":8817,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[4757,4988,634,2646,4567,53,3924,415,4732],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Cela arrivera&quot; \u2013 Arne Slot r\u00e9v\u00e8le le calendrier pr\u00e9vu de l&#039;annonce de Liverpool<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Cela arrivera&quot; \u2013 Arne Slot r\u00e9v\u00e8le le calendrier pr\u00e9vu de l&#039;annonce de Liverpool\" \/>\n<meta property=\"og:description\" content=\"Le manager de Feyenoord, Arne Slot, r\u00e9v\u00e8le que ce n&#039;est qu&#039;une \u00ab\u00a0question de jours\u00a0\u00bb avant qu&#039;il ne soit confirm\u00e9 comme successeur de Jurgen Klopp \u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/\" \/>\n<meta property=\"og:site_name\" content=\"Foot d&#039;avant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Footdavant\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-16T08:48:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-16T08:48:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/05\/Cela-arrivera-\u2013-Arne-Slot-revele-le-calendrier-prevu-de.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:site\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/\"},\"author\":{\"name\":\"Cl\u00e9ment\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\"},\"headline\":\"\u00ab\u00a0Cela arrivera\u00a0\u00bb \u2013 Arne Slot r\u00e9v\u00e8le le calendrier pr\u00e9vu de l&#39;annonce de Liverpool\",\"datePublished\":\"2024-05-16T08:48:55+00:00\",\"dateModified\":\"2024-05-16T08:48:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/\"},\"wordCount\":723,\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"keywords\":[\"Arne\",\"arrivera\",\"calendrier\",\"cela\",\"l39annonce\",\"Liverpool\",\"pr\u00e9vu\",\"r\u00e9v\u00e8le\",\"Slot\"],\"articleSection\":[\"Premier League\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/\",\"name\":\"\\\"Cela arrivera\\\" \u2013 Arne Slot r\u00e9v\u00e8le le calendrier pr\u00e9vu de l&#39;annonce de Liverpool\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\"},\"datePublished\":\"2024-05-16T08:48:55+00:00\",\"dateModified\":\"2024-05-16T08:48:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/footdavant.fr\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00a0Cela arrivera\u00a0\u00bb \u2013 Arne Slot r\u00e9v\u00e8le le calendrier pr\u00e9vu de l&#39;annonce de Liverpool\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"name\":\"Foot d'avant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\",\"name\":\"Foot d'avant\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"contentUrl\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"width\":936,\"height\":549,\"caption\":\"Foot d'avant\"},\"image\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Footdavant\/\",\"https:\/\/twitter.com\/FootdavantFr\",\"https:\/\/www.instagram.com\/footdavant.fr\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\",\"name\":\"Cl\u00e9ment\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9ment\"},\"sameAs\":[\"https:\/\/footdavant.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Cela arrivera\" \u2013 Arne Slot r\u00e9v\u00e8le le calendrier pr\u00e9vu de l&#39;annonce de Liverpool","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/","og_locale":"fr_FR","og_type":"article","og_title":"\"Cela arrivera\" \u2013 Arne Slot r\u00e9v\u00e8le le calendrier pr\u00e9vu de l&#39;annonce de Liverpool","og_description":"Le manager de Feyenoord, Arne Slot, r\u00e9v\u00e8le que ce n&#39;est qu&#39;une \u00ab\u00a0question de jours\u00a0\u00bb avant qu&#39;il ne soit confirm\u00e9 comme successeur de Jurgen Klopp \u00e0","og_url":"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/","og_site_name":"Foot d&#039;avant","article_publisher":"https:\/\/www.facebook.com\/Footdavant\/","article_published_time":"2024-05-16T08:48:55+00:00","article_modified_time":"2024-05-16T08:48:56+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/05\/Cela-arrivera-\u2013-Arne-Slot-revele-le-calendrier-prevu-de.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9ment","twitter_card":"summary_large_image","twitter_creator":"@FootdavantFr","twitter_site":"@FootdavantFr","twitter_misc":{"\u00c9crit par":"Cl\u00e9ment","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/#article","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/"},"author":{"name":"Cl\u00e9ment","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d"},"headline":"\u00ab\u00a0Cela arrivera\u00a0\u00bb \u2013 Arne Slot r\u00e9v\u00e8le le calendrier pr\u00e9vu de l&#39;annonce de Liverpool","datePublished":"2024-05-16T08:48:55+00:00","dateModified":"2024-05-16T08:48:56+00:00","mainEntityOfPage":{"@id":"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/"},"wordCount":723,"publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"keywords":["Arne","arrivera","calendrier","cela","l39annonce","Liverpool","pr\u00e9vu","r\u00e9v\u00e8le","Slot"],"articleSection":["Premier League"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/","url":"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/","name":"\"Cela arrivera\" \u2013 Arne Slot r\u00e9v\u00e8le le calendrier pr\u00e9vu de l&#39;annonce de Liverpool","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/#website"},"datePublished":"2024-05-16T08:48:55+00:00","dateModified":"2024-05-16T08:48:56+00:00","breadcrumb":{"@id":"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/footdavant.fr\/actualites\/cela-arrivera-arne-slot-revele-le-calendrier-prevu-de-lannonce-de-liverpool\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/footdavant.fr\/actualites\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00a0Cela arrivera\u00a0\u00bb \u2013 Arne Slot r\u00e9v\u00e8le le calendrier pr\u00e9vu de l&#39;annonce de Liverpool"}]},{"@type":"WebSite","@id":"https:\/\/footdavant.fr\/actualites\/#website","url":"https:\/\/footdavant.fr\/actualites\/","name":"Foot d'avant","description":"","publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/footdavant.fr\/actualites\/#organization","name":"Foot d'avant","url":"https:\/\/footdavant.fr\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","contentUrl":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","width":936,"height":549,"caption":"Foot d'avant"},"image":{"@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Footdavant\/","https:\/\/twitter.com\/FootdavantFr","https:\/\/www.instagram.com\/footdavant.fr\/"]},{"@type":"Person","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d","name":"Cl\u00e9ment","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","caption":"Cl\u00e9ment"},"sameAs":["https:\/\/footdavant.fr\/"]}]}},"_links":{"self":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/8816"}],"collection":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/comments?post=8816"}],"version-history":[{"count":1,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/8816\/revisions"}],"predecessor-version":[{"id":8818,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/8816\/revisions\/8818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media\/8817"}],"wp:attachment":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media?parent=8816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/categories?post=8816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/tags?post=8816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}