{"id":8868,"date":"2024-05-17T22:49:07","date_gmt":"2024-05-17T20:49:07","guid":{"rendered":"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/"},"modified":"2024-05-17T22:49:08","modified_gmt":"2024-05-17T20:49:08","slug":"limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united","status":"publish","type":"post","link":"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/","title":{"rendered":"Limoger Erik Ten Hag cette saison \u00ab co\u00fbterait 10 millions de livres sterling \u00e0 Manchester United \u00bb"},"content":{"rendered":"<p>Manchester United devrait verser 10 millions de livres sterling \u00e0 l&#39;entra\u00eeneur-chef Erik ten Hag et \u00e0 son \u00e9quipe s&#39;ils limogent le N\u00e9erlandais cette saison.<\/p>\n<div id=\"article_body\" itemprop=\"articleBody\">\n<h3 class=\"firstPara\">\n<strong class=\"autotag\">Manchester United<\/strong> aurait d\u00fb d\u00e9bourser 10 millions de livres sterling pour <strong class=\"autotag\">Erik Ten Hag<\/strong> et son \u00e9quipe en coulisses s&#39;ils d\u00e9cident de limoger le N\u00e9erlandais en tant qu&#39;entra\u00eeneur avant la fin de la campagne 2023-24.<\/h3>\n<p>La pression sur Ten Hag s&#39;est accrue apr\u00e8s la d\u00e9faite 4-0 de la semaine derni\u00e8re \u00e0 Crystal Palace, mais il m\u00e8nera l&#39;\u00e9quipe dimanche dans le choc de Premier League contre Arsenal, qui conteste le titre.<\/p>\n<p>Les Red Devils affronteront ensuite Newcastle United et Brighton &#038; Hove Albion lors de leurs deux derniers matches de championnat de la saison, avant d&#39;affronter Manchester City en finale de la FA Cup le 25 mai.<\/p>\n<p>Selon <em>Initi\u00e9 au football<\/em>limoger Ten Hag avant la fin de la saison co\u00fbterait aux 20 fois champions d&#39;Angleterre 10 millions de livres sterling en indemnit\u00e9s au N\u00e9erlandais et \u00e0 son \u00e9quipe en coulisses.<\/p>\n<p>Le rapport affirme que Monsieur <strong class=\"autotag\">Jim Ratcliffe<\/strong>r\u00e9cemment devenu actionnaire minoritaire d&#39;Old Trafford, \u00e9value toujours la situation manag\u00e9riale avant l&#39;\u00e9t\u00e9.<\/p>\n<p class=\"imgI\">\n<h2>L&#39;avenir de Ten Hag reste incertain<\/h2>\n<p>Ten Hag a un contrat \u00e0 Old Trafford jusqu&#39;en juin 2025, avec option d&#39;un an suppl\u00e9mentaire, mais il reste \u00e0 voir s&#39;il restera aux commandes pour le d\u00e9but de la saison 2024-25.<\/p>\n<p>Le N\u00e9erlandais pourrait mener les Red Devils \u00e0 la gloire de la FA Cup cette saison, ce qui leur assurerait une place en phase de groupes de la Ligue Europa 2024-25.<\/p>\n<p>Cependant, les Red Devils sont actuellement \u00e0 la huiti\u00e8me place du classement de la Premier League, perdant 13 fois dans l&#39;\u00e9lite anglaise au cours d&#39;une campagne d\u00e9cevante.<\/p>\n<p>Man United a \u00e9galement connu des difficult\u00e9s en Ligue des champions cette saison, terminant dernier de son groupe, ce qui l&#39;a vu quitter compl\u00e8tement l&#39;Europe \u00e0 la fin de l&#39;ann\u00e9e derni\u00e8re.<\/p>\n<p class=\"imgI\"><img decoding=\"async\" loading=\"lazy\" class=\"l\" src=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/05\/Limoger-Erik-Ten-Hag-cette-saison-couterait-10-millions.JPG\" title=\"Erik ten Hag, manager de Manchester United, le 6 mai 2024\" alt=\"Erik ten Hag, manager de Manchester United, le 6 mai 2024\" width=\"640\" height=\"480\" data-pagespeed-url-hash=\"3049832655\" onload=\"pagespeed.CriticalImages.checkImageForCriticality(this);\"><\/p>\n<h2>Ten Hag indiff\u00e9rent aux rapports de sortie<\/h2>\n<p>Ten Hag a d\u00e9clar\u00e9 lors de sa conf\u00e9rence de presse vendredi qu&#39;il n&#39;avait aucune crainte en mati\u00e8re de sortie, l&#39;homme de 54 ans \u00e9tant convaincu qu&#39;il resterait \u00e0 la t\u00eate des Diables Rouges.<\/p>\n<p>Man United a eu d&#39;importants probl\u00e8mes de blessures cette saison et Ten Hag a insist\u00e9 sur le fait que les propri\u00e9taires sont pleinement conscients des d\u00e9fis auxquels il a \u00e9t\u00e9 confront\u00e9 au cours de la campagne en cours.<\/p>\n<p>\u00ab\u00a0Le [owners] avoir du bon sens.  Vous voyez, quand nous avons 32 lignes arri\u00e8res diff\u00e9rentes, nous avons utilis\u00e9 13 partenariats dans la moiti\u00e9 centrale, quand ils voient que nous n&#39;avons pas d&#39;arri\u00e8re gauche, ils savent que cela aura un impact n\u00e9gatif sur les r\u00e9sultats\u00a0\u00bb, a-t-il d\u00e9clar\u00e9 aux journalistes.<\/p>\n<p>\u00ab\u00a0C&#39;est une \u00e9norme finale de FA Cup. Nous sommes heureux d&#39;y \u00eatre. Cela peut \u00eatre un moment fort de cette saison. Nous savons que les raisons pour lesquelles nous sous-performons sont \u00e0 cause des blessures. Aucune \u00e9quipe ne sera performante si vous avez autant de blessures dans des domaines cl\u00e9s. \u00ab\u00a0.<\/p>\n<p><strong class=\"autotag\">Thomas Tuchel<\/strong>qui quitte le Bayern Munich cet \u00e9t\u00e9, reste le favori pour remplacer Ten Hag, en cas de changement, tandis que l&#39;entra\u00eeneur-chef de l&#39;Angleterre <strong class=\"autotag\">Gareth Southgate<\/strong> et ancien manager de Chelsea <strong class=\"autotag\">Graham Potter<\/strong> sont \u00e9galement consid\u00e9r\u00e9s comme des rempla\u00e7ants possibles du patron actuel.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Manchester United devrait verser 10 millions de livres sterling \u00e0 l&#39;entra\u00eeneur-chef Erik ten Hag et \u00e0 son \u00e9quipe s&#39;ils limogent le N\u00e9erlandais cette saison. Manchester<\/p>\n","protected":false},"author":1,"featured_media":8869,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[1222,5005,190,192,694,115,11,114,482,116,191,13],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Limoger Erik Ten Hag cette saison \u00ab co\u00fbterait 10 millions de livres sterling \u00e0 Manchester United \u00bb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Limoger Erik Ten Hag cette saison \u00ab co\u00fbterait 10 millions de livres sterling \u00e0 Manchester United \u00bb\" \/>\n<meta property=\"og:description\" content=\"Manchester United devrait verser 10 millions de livres sterling \u00e0 l&#039;entra\u00eeneur-chef Erik ten Hag et \u00e0 son \u00e9quipe s&#039;ils limogent le N\u00e9erlandais cette saison. Manchester\" \/>\n<meta property=\"og:url\" content=\"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/\" \/>\n<meta property=\"og:site_name\" content=\"Foot d&#039;avant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Footdavant\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-17T20:49:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-17T20:49:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/05\/Limoger-Erik-Ten-Hag-cette-saison-couterait-10-millions.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:site\" content=\"@FootdavantFr\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/\"},\"author\":{\"name\":\"Cl\u00e9ment\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\"},\"headline\":\"Limoger Erik Ten Hag cette saison \u00ab co\u00fbterait 10 millions de livres sterling \u00e0 Manchester United \u00bb\",\"datePublished\":\"2024-05-17T20:49:07+00:00\",\"dateModified\":\"2024-05-17T20:49:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/\"},\"wordCount\":593,\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"keywords\":[\"cette\",\"co\u00fbterait\",\"Erik\",\"Hag\",\"limoger\",\"livres\",\"Manchester\",\"millions\",\"saison\",\"sterling\",\"ten\",\"United\"],\"articleSection\":[\"Premier League\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/\",\"name\":\"Limoger Erik Ten Hag cette saison \u00ab co\u00fbterait 10 millions de livres sterling \u00e0 Manchester United \u00bb\",\"isPartOf\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\"},\"datePublished\":\"2024-05-17T20:49:07+00:00\",\"dateModified\":\"2024-05-17T20:49:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/footdavant.fr\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Limoger Erik Ten Hag cette saison \u00ab co\u00fbterait 10 millions de livres sterling \u00e0 Manchester United \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#website\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"name\":\"Foot d'avant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#organization\",\"name\":\"Foot d'avant\",\"url\":\"https:\/\/footdavant.fr\/actualites\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"contentUrl\":\"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png\",\"width\":936,\"height\":549,\"caption\":\"Foot d'avant\"},\"image\":{\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Footdavant\/\",\"https:\/\/twitter.com\/FootdavantFr\",\"https:\/\/www.instagram.com\/footdavant.fr\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d\",\"name\":\"Cl\u00e9ment\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9ment\"},\"sameAs\":[\"https:\/\/footdavant.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Limoger Erik Ten Hag cette saison \u00ab co\u00fbterait 10 millions de livres sterling \u00e0 Manchester United \u00bb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/","og_locale":"fr_FR","og_type":"article","og_title":"Limoger Erik Ten Hag cette saison \u00ab co\u00fbterait 10 millions de livres sterling \u00e0 Manchester United \u00bb","og_description":"Manchester United devrait verser 10 millions de livres sterling \u00e0 l&#39;entra\u00eeneur-chef Erik ten Hag et \u00e0 son \u00e9quipe s&#39;ils limogent le N\u00e9erlandais cette saison. Manchester","og_url":"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/","og_site_name":"Foot d&#039;avant","article_publisher":"https:\/\/www.facebook.com\/Footdavant\/","article_published_time":"2024-05-17T20:49:07+00:00","article_modified_time":"2024-05-17T20:49:08+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2024\/05\/Limoger-Erik-Ten-Hag-cette-saison-couterait-10-millions.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9ment","twitter_card":"summary_large_image","twitter_creator":"@FootdavantFr","twitter_site":"@FootdavantFr","twitter_misc":{"\u00c9crit par":"Cl\u00e9ment","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/#article","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/"},"author":{"name":"Cl\u00e9ment","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d"},"headline":"Limoger Erik Ten Hag cette saison \u00ab co\u00fbterait 10 millions de livres sterling \u00e0 Manchester United \u00bb","datePublished":"2024-05-17T20:49:07+00:00","dateModified":"2024-05-17T20:49:08+00:00","mainEntityOfPage":{"@id":"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/"},"wordCount":593,"publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"keywords":["cette","co\u00fbterait","Erik","Hag","limoger","livres","Manchester","millions","saison","sterling","ten","United"],"articleSection":["Premier League"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/","url":"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/","name":"Limoger Erik Ten Hag cette saison \u00ab co\u00fbterait 10 millions de livres sterling \u00e0 Manchester United \u00bb","isPartOf":{"@id":"https:\/\/footdavant.fr\/actualites\/#website"},"datePublished":"2024-05-17T20:49:07+00:00","dateModified":"2024-05-17T20:49:08+00:00","breadcrumb":{"@id":"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/footdavant.fr\/actualites\/limoger-erik-ten-hag-cette-saison-couterait-10-millions-de-livres-sterling-a-manchester-united\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/footdavant.fr\/actualites\/"},{"@type":"ListItem","position":2,"name":"Limoger Erik Ten Hag cette saison \u00ab co\u00fbterait 10 millions de livres sterling \u00e0 Manchester United \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/footdavant.fr\/actualites\/#website","url":"https:\/\/footdavant.fr\/actualites\/","name":"Foot d'avant","description":"","publisher":{"@id":"https:\/\/footdavant.fr\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/footdavant.fr\/actualites\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/footdavant.fr\/actualites\/#organization","name":"Foot d'avant","url":"https:\/\/footdavant.fr\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","contentUrl":"https:\/\/footdavant.fr\/actualites\/wp-content\/uploads\/2023\/09\/Copy-of-FootDavant-Logo.png","width":936,"height":549,"caption":"Foot d'avant"},"image":{"@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Footdavant\/","https:\/\/twitter.com\/FootdavantFr","https:\/\/www.instagram.com\/footdavant.fr\/"]},{"@type":"Person","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/bc222566d95871b37e597b3ed3ba5e1d","name":"Cl\u00e9ment","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/footdavant.fr\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7728b29aac2719421e1a9159b2254c44?s=96&d=mm&r=g","caption":"Cl\u00e9ment"},"sameAs":["https:\/\/footdavant.fr\/"]}]}},"_links":{"self":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/8868"}],"collection":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/comments?post=8868"}],"version-history":[{"count":1,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/8868\/revisions"}],"predecessor-version":[{"id":8870,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/posts\/8868\/revisions\/8870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media\/8869"}],"wp:attachment":[{"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/media?parent=8868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/categories?post=8868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/footdavant.fr\/actualites\/wp-json\/wp\/v2\/tags?post=8868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}